{"id":97530,"date":"2020-01-12T15:22:02","date_gmt":"2020-01-12T15:22:02","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2020\/01\/12\/sandra-echeverria-es-de-armas-tomar\/"},"modified":"2020-01-12T15:22:02","modified_gmt":"2020-01-12T15:22:02","slug":"sandra-echeverria-es-de-armas-tomar","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/sandra-echeverria-es-de-armas-tomar\/","title":{"rendered":"SANDRA ECHEVERR\u00cdA ES DE ARMAS TOMAR\u2028\u2028"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0Ser\u00e1 la encargada de protagonizar la teleserie &#8220;La bandida&#8221;, basada en la historia de la famosa Graciela Olmos\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>La actriz Sandra Echeverr\u00eda ser\u00e1 la encargada de protagonizar la teleserie &#8220;La bandida&#8221;, basada en la historia de la famosa Graciela Olmos, mujer con un poder particular entre revolucionarios, pol\u00edticos e intelectuales del M\u00e9xico bronco y urbano post revolucionario.\u2028La teleserie, conformada por 70 episodios, dar\u00e1 inicio el pr\u00f3ximo 13 de enero, a las 20:00 horas, por Telemundo Internacional.\u2028&#8221;Rebelde, hu\u00e9rfana y empoderada ante la injusticia, en su infancia logr\u00f3 sobrevivir a la Revoluci\u00f3n mexicana en su natal Chihuahua, gracias a su car\u00e1cter y habilidad como ladrona, apostadora, hasta convertirse en toda una mujer, due\u00f1a de uno de los prost\u00edbulos m\u00e1s selectos de la antigua Ciudad de M\u00e9xico, en donde su poder aument\u00f3, particularmente para persuadir a pol\u00edticos, ex revolucionarios e intelectuales, clientes asiduos todos ellos&#8221;, explica la productora en un comunicado.\u2028En &#8220;La bandida&#8221; hay vestuario y escenograf\u00eda de esa \u00e9poca y aborda &#8220;(como pocas veces en la televisi\u00f3n) un lado B de la historia mexicana, con una perspectiva muy privada, ahora con la participaci\u00f3n de la actriz y cantante Sandra Echeverr\u00eda, como Graciela Olmos, quien tambi\u00e9n interpreta el tema &#8220;Bandida&#8221;.\u2028En pantalla se ver\u00e1 a Julieta Grajales, como la revolucionaria Marina Ahedo; Jenny Kay, como la ni\u00f1a Marina Ahedo; Ianis Guerrero, como Jos\u00e9 Hern\u00e1ndez; el venezolano Albi de Abreu, como Tommy Harton; el actor Iv\u00e1n Arana, como Pedro N\u00fa\u00f1ez; Marcia Couti\u00f1o, como &#8220;la hermana Catalina&#8221;, entre otros talentos.<br \/>La actriz Sandra Echeverr\u00eda ser\u00e1 la encargada de protagonizar la teleserie &#8220;La bandida&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0Ser\u00e1 la encargada de protagonizar la teleserie &#8220;La bandida&#8221;, basada en la historia de la famosa Graciela Olmos\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-97530","post","type-post","status-publish","format-standard","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/97530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=97530"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/97530\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=97530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=97530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=97530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}