{"id":92956,"date":"2019-10-21T20:07:01","date_gmt":"2019-10-21T20:07:01","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/10\/21\/inicia-el-viernes-la-noche-de-leyendas-en-el-panteon-municipal\/"},"modified":"2019-10-21T20:07:01","modified_gmt":"2019-10-21T20:07:01","slug":"inicia-el-viernes-la-noche-de-leyendas-en-el-panteon-municipal","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/inicia-el-viernes-la-noche-de-leyendas-en-el-panteon-municipal\/","title":{"rendered":"Inicia el viernes la Noche de Leyendas en el Pante\u00f3n Municipal"},"content":{"rendered":"<p>Se llevar\u00e1 a cabo a partir del 25 de octubre y hasta el 9 de noviembre <!--more--> <\/p>\n<p><p>  En ocasi\u00f3n de la celebraci\u00f3n de D\u00eda de Muertos y con la intenci\u00f3n de preservar y difundir nuestras tradiciones, la Presidencia Municipal de Pachuca, a trav\u00e9s de la Secretar\u00eda de Desarrollo Econ\u00f3mico, llevar\u00e1 a cabo a partir del 25 de octubre y hasta el 9 de noviembre la S\u00e9ptima Temporada de Noche de Leyendas en el Pante\u00f3n Municipal.<\/p>\n<p>  Este programa, tiene la caracter\u00edstica distintiva que los asistentes recorren las tumbas por la noche, acompa\u00f1ados de gu\u00edas de Turismo Pachuca quienes adem\u00e1s de disfrazarse para la ocasi\u00f3n,  narran antiguos relatos de misterio de la capital hidalguense.<\/p>\n<p>  Cada uno de los recorridos tiene una duraci\u00f3n de una hora y en octubre se efectuar\u00e1n: viernes 25, s\u00e1bado 26, lunes 28, martes 29, mi\u00e9rcoles 30 y jueves 31.<\/p>\n<p>   Las opciones para noviembre son: viernes 1 y 8, as\u00ed como s\u00e1bados 2 y 9. <\/p>\n<p>  En ambos casos hay tres horarios: 20:00, 21:30 y 23:00 horas. Los boletos tienen un costo de 55 pesos y est\u00e1n a la venta en la tienda de ubicada en la planta baja de El Reloj Monumental, en M\u00f3dulo de informaci\u00f3n tur\u00edstica de  Plaza Galer\u00eda o v\u00eda TicketPoint (en este caso se cobra con comisi\u00f3n).<\/p>\n<p>  Para mayor informaci\u00f3n comunicarse al 7 18 83 02 extensiones 18 a la 21 o en Facebook @PACHUCAMUNICIPIO O @TURISMOPACHUCA.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Se llevar\u00e1 a cabo a partir del 25 de octubre y hasta el 9 de noviembre<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-92956","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/92956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=92956"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/92956\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=92956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=92956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=92956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}