{"id":91824,"date":"2019-10-01T14:48:38","date_gmt":"2019-10-01T14:48:38","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/10\/01\/el-cuerpo-de-jose-jose-no-desaparecio-y-ya-lo-estan-velando\/"},"modified":"2019-10-01T14:48:38","modified_gmt":"2019-10-01T14:48:38","slug":"el-cuerpo-de-jose-jose-no-desaparecio-y-ya-lo-estan-velando","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/el-cuerpo-de-jose-jose-no-desaparecio-y-ya-lo-estan-velando\/","title":{"rendered":"El cuerpo de Jos\u00e9 Jos\u00e9 no desapareci\u00f3 y ya lo est\u00e1n velando"},"content":{"rendered":"<p>El cuerpo de Jos\u00e9 Jos\u00e9 es velado desde el lunes en la funeraria &#8220;Caballero Rivero&#8221; en la ciudad de Miami, Florida. <!--more--> <\/p>\n<p>  Algunas voces han sugerido que no se encuentra ah\u00ed, lo cierto es que esta funeraria tiene varias sucursales en la misma ciudad y de manera confiable El Universal pudo comprobar a trav\u00e9s de una persona cercana a los dolientes que el Pr\u00edncipe de la canci\u00f3n est\u00e1 siendo velado en la sucursal de Westchester.<\/p>\n<p>  &#8220;El cuerpo nunca desapareci\u00f3 y nunca estuvo perdido&#8221; coment\u00f3 la fuente que pidi\u00f3 el anonimato. Anteriormente uno de los guardias que resguardan el ingreso a la capilla donde est\u00e1n parte de los familiares del artista, confirm\u00f3 que ah\u00ed estaba el ata\u00fad que guarda los restos de Jos\u00e9 Jos\u00e9 y que ten\u00edan prohibido permitir el paso a personas no autorizadas o a la prensa.<\/p>\n<p>  La especulaci\u00f3n que corri\u00f3 desde la llegada a Miami de Jos\u00e9 Joel y Marysol, hijos mayores del cantante, desde la madrugada del domingo, acerca de una eventual desaparici\u00f3n del cuerpo del artista o el pleno desconocimiento de todos sobre su paradero, se debe a que las leyes sobre una persona fallecida y sus deudos legales es muy estricta en la Uni\u00f3n Americana.<\/p>\n<p>  &#8220;La familia que estuvo cuando falleci\u00f3 el cantante: su \u00faltima esposa y la hija con quien viv\u00eda -Sara Sosa-, son quienes tienen el poder legal por ley, pero otorgado adem\u00e1s por el fallecido y son quienes deciden qu\u00e9 hacer y qu\u00e9 no hacer o qu\u00e9 decir y qu\u00e9 no decir&#8221;, comenta la fuente consultada.<\/p>\n<p>  &#8220;Estados Unidos es muy diferente a M\u00e9xico, aqu\u00ed todo se maneja por escrito y son muy rigurosos; ning\u00fan hospital o funeraria te va a dar informaci\u00f3n de nada porque podr\u00edan ser sujetos a serias demandas que les costar\u00edan mucho dinero, es lo que se llama acuerdos de confidencialidad y est\u00e1n firmados&#8221;, a\u00f1ade.<\/p>\n<p>  Lo anterior explica por qu\u00e9 Jos\u00e9 Joel y Marysol no pudieron recibir informaci\u00f3n en el hospital, ni en el departamento de polic\u00eda, ni en la funeraria. A nadie que no sean los deudos legales se les da informaci\u00f3n sin autorizaci\u00f3n escrita, incluida la prensa.<\/p>\n<p>  El Consulado General de M\u00e9xico en Miami confirm\u00f3 a El Universal que los deudos, en este caso, todos los hijos y familiares directos \u2014de M\u00e9xico y Miami\u2014, &#8220;tienen que ponerse de acuerdo de qu\u00e9 van a hacer, a nosotros a\u00fan no nos han pedido el apoyo consular.<\/p>\n<p>  Nosotros hemos estado muy pendientes de ellos desde que se supo la noticia, pero a\u00fan no solicitan el tr\u00e1mite para llevar el cuerpo o las cenizas, seg\u00fan sea el caso, a la Ciudad de M\u00e9xico, donde todos esperamos que los mexicanos puedan despedirse de este gran artista.<\/p>\n<p>  &#8220;Estamos en espera para poderlos asistir en lo que corresponde al Consulado de M\u00e9xico en Miami&#8221;.<\/p>\n<p>  El Consulado de M\u00e9xico en Miami tambi\u00e9n confirm\u00f3 que ya hab\u00edan ofrecido las condolencias a nombre del Presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, as\u00ed como la recomendaci\u00f3n para que Jos\u00e9 Jos\u00e9 fuera llevado a M\u00e9xico para que el p\u00fablico se despida del Pr\u00edncipe de la canci\u00f3n.<\/p>\n<p>  Anuncian homenaje en M\u00e9xico. Alejandra Frausto, titular de la Secretar\u00eda de Cultura federal, inform\u00f3 que est\u00e1 en proceso un homenaje p\u00f3stumo para el artista.<\/p>\n<p>  &#8220;Estamos conformando un homenaje digno para Jos\u00e9 Jos\u00e9; para ello estamos trabajando en coordinaci\u00f3n con la familia porque siempre trabajamos de la mano con ellos, pero por ahora vamos a respetar estos momentos de intimidad que nos pidieron&#8221;, dijo la secretaria.<\/p>\n<p>  La funcionaria hizo la declaraci\u00f3n en las oficinas de la Secretar\u00eda de Cultura de la Ciudad de M\u00e9xico (Arenal 40), donde tambi\u00e9n habl\u00f3 sobre la importancia del artista pero no mencion\u00f3 si los planes del reconocimiento podr\u00edan ser en el Palacio de Bellas Artes, como ha ocurrido con figuras como Juan Gabriel y Mar\u00eda F\u00e9lix.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>El cuerpo de Jos\u00e9 Jos\u00e9 es velado desde el lunes en la funeraria &#8220;Caballero Rivero&#8221; en la ciudad de Miami, Florida.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-91824","post","type-post","status-publish","format-standard","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/91824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=91824"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/91824\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=91824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=91824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=91824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}