{"id":91822,"date":"2019-10-01T12:31:21","date_gmt":"2019-10-01T12:31:21","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/10\/01\/premio-nobel-apuesta-por-capitalismo-que-se-oponga-a-monopolios-2\/"},"modified":"2019-10-01T12:31:21","modified_gmt":"2019-10-01T12:31:21","slug":"premio-nobel-apuesta-por-capitalismo-que-se-oponga-a-monopolios-2","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/premio-nobel-apuesta-por-capitalismo-que-se-oponga-a-monopolios-2\/","title":{"rendered":"Premio Nobel apuesta por capitalismo que se oponga a monopolios"},"content":{"rendered":"<p>N\u00daMEROS CLAROS<br \/>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0El desarrollo actual del capitalismo ha conducido a profundizar la desigualdad social en todo el mundo, concentrando la riqueza en unas cuantas manos\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>El premio nobel de econom\u00eda Joseph Stiglitz, en su \u00faltimo libro titulado: \u201cGente, poder y ganancias\u201d, defiende un modelo de capitalismo progresivo que lucha contra los monopolios y devuelve el poder a los empleados, defini\u00e9ndose como un liberal que apuesta por los dem\u00f3cratas estadounidenses en las pr\u00f3ximas elecciones, frente a un presidente republicano que pretende llevar al pasado al capitalismo, a la era de las barreras arancelarias y el aislamiento de las econom\u00edas nacionales detr\u00e1s de sus muros de aranceles y cuotas a las importaciones.<br \/>El desarrollo actual del capitalismo ha conducido a profundizar la desigualdad social en todo el mundo, concentrando la riqueza en unas cuantas manos. El Premio Nobel de Econom\u00eda en 2001, tiene claro que la concentraci\u00f3n del 20% de la riqueza en el 1% de los estadounidenses, ha conducido a un aumento de la desigualdad; \u00e9l ha se\u00f1alado en una reciente entrevista que \u201cel poder de mercado de algunas grandes empresas estadounidenses conduce a un aumento de la desigualdad, lo que permite a los m\u00e1s ricos ejercer presi\u00f3n pol\u00edtica. De este modo, pueden obtener el voto de las leyes que les son favorables, que benefician el capitalismo de los rentistas en lugar de la creaci\u00f3n de riqueza para todo el pa\u00eds.\u201d, con lo cual podr\u00edan estar poniendo en peligro para la democracia, sin duda alguna.<br \/>El Dr. Joseph Stiglitz propone refundar el capitalismo; tal como en 2008 m\u00e1s de un l\u00edder europeo lo hizo entonces, durante la crisis de los cr\u00e9ditos basura: \u201cSubprime\u201d. El premio nobel propone \u201cun nuevo contrato social, con nuevos v\u00ednculos entre el mercado, el Estado y la sociedad civil.\u201d; al respecto, el Dr Stiglitz ha planteado que \u201cEl mercado es una parte importante de la ecuaci\u00f3n, pero no se trata de un capitalismo sin obst\u00e1culos donde se cree que los mercados resuelven todos los problemas y el Estado es el problema.\u201d, precisa.<br \/>El premio nobel de econom\u00eda afirma que el capitalismo de la globalizaci\u00f3n se caracteriza por la profundizaci\u00f3n de la desigualdad. Stiglitz se\u00f1ala que \u201ceste capitalismo ha engendrado un fuerte crecimiento de las desigualdades, una disminuci\u00f3n de la vida \u00fatil, desastres ecol\u00f3gicos; todos esos son los s\u00edntomas de algo que no funciona bien.\u201d Por lo que se\u00f1ala que, de lo que \u00e9l habla \u201cno es muy diferente de la socialdemocracia europea&#8230; y no es dif\u00edcil de implementar.\u201d, pues s\u00f3lo \u201cEs necesario reducir el exceso de poder de los monopolios, dar un poder de negociaci\u00f3n a los empleados, acelerar las reformas del gobierno corporativo.\u201d, precisa.<br \/>De aqu\u00ed que el Dr. Joseph Stiglitz afirme que \u201csi los dem\u00f3cratas ganan la Casa Blanca, la C\u00e1mara y el Senado,\u201d s\u00f3lo les tomar\u00eda dos a\u00f1os implementar las medidas para cambiar el rostro del capitalismo actual. \u00c9l precisa que debemos tener en cuenta \u201cque el debate est\u00e1 cambiando muy r\u00e1pidamente en los Estados Unidos.\u201d, por lo que reformar la econom\u00eda de mercado podr\u00eda conducir a desarrollar un nuevo concepto, el de \u201ccapitalismo progresista\u201d; nada nuevo, se trata de un capitalismo socialdem\u00f3crata que ha permitido a pa\u00edses como Suecia convertirse en una potencia econ\u00f3mica y cultural, uno de los pa\u00edses con mayor bienestar social.<br \/>El Dr. Joseph Stiglitz se\u00f1ala que si bien Elizabeth Warren est\u00e1 considerando un impuesto del 2% sobre herencias superiores a 50 millones de d\u00f3lares; mientras que Thomas Piketty ofrece un impuesto m\u00e1s alto, \u00e9l apoya la primera de las propuestas, pues en su opini\u00f3n \u201cuna tasa impositiva moderada evitar\u00e1 que los multimillonarios pasen demasiado tiempo tratando de evitar pagar este impuesto. Hombres como Jeff Bezos o Bill Gates quieren crear negocios poderosos que dominen a otros.\u201d; por lo que s\u00ed se les \u201cdice a estas dos personas que no tendr\u00e1n 100 mil millones de d\u00f3lares sino 20 mil millones de d\u00f3lares,\u201d estar\u00e1n dispuestos a aportar ese dinero, pues en el mercado tratan de ser los primeros y como hombres, siempre est\u00e1n dispuestos a dar algo de su dinero.<br \/>En la entrevista, Joseph Stiglitz se\u00f1ala que \u201cdebemos ir m\u00e1s all\u00e1 de la econom\u00eda, incluso si sigue siendo importante. Polonia, por ejemplo, ha causado muchos males a los europeos, especialmente con sus elecciones pol\u00edticas. De todos los pa\u00edses de Europa del Este, es el \u00fanico que tiene un verdadero \u00e9xito econ\u00f3mico. Pero a pesar de que el pa\u00eds est\u00e1 bien, todav\u00eda hay focos de personas bajo tensi\u00f3n. La iron\u00eda es que los l\u00edderes pol\u00edticos encuentran chivos expiatorios, como el comercio internacional y los migrantes. Por extra\u00f1o que parezca, estos son los lugares donde los inmigrantes son m\u00e1s temidos de que no haya ninguno. El verdadero problema no es la inmigraci\u00f3n sino la emigraci\u00f3n. Es la despoblaci\u00f3n la que ha causado este miedo. Esto causa desorganizaci\u00f3n social\u201d, afirma el premio nobel de econom\u00eda.<br \/>Cu\u00e1ndo le preguntan si \u00e9l creer\u00eda que la situaci\u00f3n econ\u00f3mica de 2019 se parece a la de 2008, el Dr. Stiglitz afirm\u00f3 que \u201cno hay duda de que la econom\u00eda mundial se est\u00e1 desacelerando. Pero en 2008, tuvimos un gran problema en los cientos de miles de millones de d\u00f3lares: el sector financiero. Hoy, tenemos una multitud de problemas diferentes, menos propensos a causar una crisis. China debe hacer su transici\u00f3n econ\u00f3mica de una industria basada en la exportaci\u00f3n a servicios que depender\u00e1n de la demanda interna. Europa tiene un problema con el euro que ha llevado a la austeridad fiscal cuando era in\u00fatil. En pocas palabras, el problema de Europa es Alemania y su concepci\u00f3n de la pol\u00edtica econ\u00f3mica. Estados Unidos tiene un problema: Trump. Dame un pa\u00eds con desigualdades tan altas que decida reducir los impuestos para los multimillonarios, lo que elimina el seguro de salud de millones de ciudadanos, donde las personas se disparan entre s\u00ed, pero se niegan a controlar las armas. fuego. A esto se suma la guerra comercial, las tensiones en Cachemira, las de Ir\u00e1n. Nada de esto habr\u00eda sucedido con un gobierno estadounidense m\u00e1s estable. Trump les da a los aut\u00f3cratas el derecho de hacer lo que quieran\u201d. Puntualiz\u00f3, afirmando que \u201cla pol\u00edtica econ\u00f3mica de Trump es realmente mala\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00daMEROS CLAROS\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0El desarrollo actual del capitalismo ha conducido a profundizar la desigualdad social en todo el mundo, concentrando la riqueza en unas cuantas manos\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-91822","post","type-post","status-publish","format-standard","hentry","category-jose-luis-ortiz-santillan"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/91822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=91822"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/91822\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=91822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=91822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=91822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}