{"id":91704,"date":"2019-09-29T13:51:15","date_gmt":"2019-09-29T13:51:15","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/09\/29\/muere-jose-jose-a-los-71-anos\/"},"modified":"2019-09-29T13:51:15","modified_gmt":"2019-09-29T13:51:15","slug":"muere-jose-jose-a-los-71-anos","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/muere-jose-jose-a-los-71-anos\/","title":{"rendered":"MUERE JOS\u00c9 JOS\u00c9 A LOS 71 A\u00d1OS"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0Jos\u00e9 R\u00f3mulo Sosa Ortiz, como era su nombre real, siempre dijo que quien lo ense\u00f1\u00f3 a acoplarse a la industria musical fue Pedro Vargas\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>El cantante Jos\u00e9 Jos\u00e9 falleci\u00f3 a los 71 a\u00f1os de edad, la noticia fue confirmada por la periodista Mara Patricia Casta\u00f1eda.\u2028Jos\u00e9 R\u00f3mulo Sosa Ortiz, como era su nombre real, siempre dijo que quien lo ense\u00f1\u00f3 a acoplarse a la industria musical fue Pedro Vargas.\u2028M\u00e1s de cincuenta a\u00f1os de carrera lo avalaron desde que inici\u00f3 tocando la guitarra, dando serenatas y present\u00e1ndose en centros nocturnos. El nacido en la Ciudad de M\u00e9xico vendi\u00f3 m\u00e1s de 120 millones de copias alrededor del mundo Y alcanz\u00f3 la fama muy pronto, pero luego la fama lo alcanz\u00f3 a \u00e9l.\u2028Tal vez la OTI y su interpretaci\u00f3n de &#8220;El triste&#8221;, en 1970, le dieron una de las mayores alegr\u00edas en su vida ya que consigui\u00f3 el tercer lugar. Pero ten\u00eda destinado el estrellato, siendo la d\u00e9cada de los ochentas en la cual ver\u00eda su mayor esplendor.\u2028El reconocimiento le vali\u00f3 varias nominaciones a los premios Grammy y una estrella en el Paseo de la Fama de Hollywood. Pero como todo lo bueno que le pas\u00f3, tambi\u00e9n vivi\u00f3 momentos de desesperanza con sus problemas de alcoholismo, tal como tambi\u00e9n vivi\u00f3 su padre, adicci\u00f3n que le caus\u00f3 graves problemas financieros. Cuando lleg\u00f3 al l\u00edmite decidi\u00f3 internarse en el Centro de Rehabilitaci\u00f3n y Universidad Heizelden en Minessota, Estados Unidos.\u2028Pero su carrera no fue la misma. Las afecciones lo persiguieron una y otra vez, ya sea por la enfermedad de Lyme por cerca de nueve a\u00f1os, una par\u00e1lisis facial o algunas ca\u00eddas, una de ellas en el escenario en 2013.\u2028&#8221;Desde ni\u00f1o fui enfermizo, nac\u00ed muy chiquito y creyeron que no lo iba a lograr pero gracias a la leche materna es que pude sobrevivir aunque siempre con problemas de salud como la herencia pulmonar, am\u00edgdalas, entre otros&#8221;, record\u00f3 alguna vez.\u2028Cada tanto deb\u00eda ir a una revisi\u00f3n m\u00e9dica, pues le detectaron alergia a 22 elementos entre ellos el aire acondicionado. Para Jos\u00e9 Jos\u00e9 no fue nada f\u00e1cil descubrir que hab\u00eda perdido su voz, esa misma que lo hizo alcanzar la gloria a\u00f1os atr\u00e1s.\u2028De pronto deb\u00eda usar plantillas en los zapatos, ox\u00edgeno, un bast\u00f3n, se hizo m\u00e1s flaco y se le dificultaba caminar. Una voz heredada por un tenor como lo fue su padre estaba ronca ahora. &#8220;He pasado por diversas circunstancias porque Dios as\u00ed lo quiso, pero he encontrado la manera de seguir trabajando hasta que Dios diga, porque \u00e9l tiene la \u00faltima palabra&#8221;, conversaba quien a ra\u00edz de sus enfermedades viv\u00eda casi al d\u00eda.<br \/>El nacido en la Ciudad de M\u00e9xico vendi\u00f3 m\u00e1s de 120 millones de copias alrededor del mundo y alcanz\u00f3 la fama muy pronto, pero luego la fama lo alcanz\u00f3 a \u00e9l.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0Jos\u00e9 R\u00f3mulo Sosa Ortiz, como era su nombre real, siempre dijo que quien lo ense\u00f1\u00f3 a acoplarse a la industria musical fue Pedro Vargas\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-91704","post","type-post","status-publish","format-standard","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/91704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=91704"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/91704\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=91704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=91704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=91704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}