{"id":90192,"date":"2019-09-02T22:52:34","date_gmt":"2019-09-02T22:52:34","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/09\/02\/fgr-reactiva-investigacion-de-caso-de-la-guarderia-abc\/"},"modified":"2019-09-02T22:52:34","modified_gmt":"2019-09-02T22:52:34","slug":"fgr-reactiva-investigacion-de-caso-de-la-guarderia-abc","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/fgr-reactiva-investigacion-de-caso-de-la-guarderia-abc\/","title":{"rendered":"FGR reactiva investigaci\u00f3n de caso de la &#8220;Guarder\u00eda ABC&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El director del IMSS explic\u00f3 que en la ratificaci\u00f3n de la denuncia presentada por el instituto el pasado 22 de mayo, por la probable responsabilidad del exgobernador Eduardo Bours (PRI), la Fiscal\u00eda considere la investigaci\u00f3n que llev\u00f3 a cabo en su momento la SCJN.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El director del IMSS, Zo\u00e9 Robledo inform\u00f3 que la Fiscal\u00eda General de la Rep\u00fablica reactiv\u00f3 ya la investigaci\u00f3n en torno el caso del incendio de la &#8220;Guarder\u00eda ABC&#8221; de Hermosillo, donde murieron 49 ni\u00f1os y decenas m\u00e1s resultaron heridos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Tras una reuni\u00f3n del presidente Andr\u00e9s Manuel L\u00f3pez Obrador con padres y madres de los ni\u00f1os de la &#8220;Guarder\u00eda ABC&#8221;, Robledo Aburto expres\u00f3: &#8220;Est\u00e1 reactivada yo ir\u00e9 informando cuando hagamos la ampliaci\u00f3n&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Durante la reuni\u00f3n con los padres de familia ambas partes concretaron que todos los menores que resultaron con lesiones reciban atenci\u00f3n m\u00e9dica por parte del IMSS y adem\u00e1s se habl\u00f3 de la posibilidad de construir un memorial para recodar a las v\u00edctimas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El director del IMSS explic\u00f3 que en la ratificaci\u00f3n de la denuncia presentada por el instituto el pasado 22 de mayo, por la probable responsabilidad del exgobernador Eduardo Bours (PRI), la Fiscal\u00eda considere la investigaci\u00f3n que llev\u00f3 a cabo en su momento la SCJN.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">&#8220;La denuncia presentada por Germ\u00e1n Mart\u00ednez es contra el exgobernador, pero nosotros estamos empleando tambi\u00e9n a los particulares porque no puede haber justicia si no se incluye los due\u00f1os de esta guarder\u00eda&#8221;, dijo.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director del IMSS explic\u00f3 que en la ratificaci\u00f3n de la denuncia presentada por el instituto el pasado 22 de mayo, por la probable responsabilidad del exgobernador Eduardo Bours (PRI), la Fiscal\u00eda considere la investigaci\u00f3n que llev\u00f3 a cabo en su momento la SCJN.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-90192","post","type-post","status-publish","format-standard","hentry","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/90192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=90192"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/90192\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=90192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=90192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=90192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}