{"id":89683,"date":"2019-08-25T14:47:23","date_gmt":"2019-08-25T14:47:23","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/08\/25\/cartas-fatales\/"},"modified":"2019-08-25T14:47:23","modified_gmt":"2019-08-25T14:47:23","slug":"cartas-fatales","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/cartas-fatales\/","title":{"rendered":"Cartas fatales"},"content":{"rendered":"<p>CINE DE HOY<\/p>\n<p>  <!--more-->  <\/p>\n<p>La cinta encargada de inaugurar en la Cineteca Nacional, el XVIII Festival Internacional de Cine de Horror de la Ciudad de M\u00e9xico, fue la canadiense Red letter day de Cameron MacGowan.<br \/>De acuerdo al gui\u00f3n del propio director, los Edwards llegan a vivir a un nuevo vecindario, tras el divorcio de la madre Melanie (Dawn van de Schoot), y el descontrol de sus hijos adolescentes Timothy (Kaeleb Zain Gartner) y Madison (Hailey Foss).<br \/>Esta muestra su rebeld\u00eda saliendo con el repulsivo Luther (Roger Le blanc).<br \/>Pero la tranquilidad del lugar se ve afectada por el env\u00edo de unas cartas rojas, en la que se les pide matar a una persona, antes de que \u00e9sta las mate.<br \/>Melanie toma el asunto a broma, pues se le pide que mate a su mejor amiga, pero Lewis (Michael Tan), el esposo de esta, provoca que las cosas se salgan de control. <br \/>Todo empeora, cuando Madison se entera de que debe matar a Luther, pero \u00e9ste se le adelanta.<br \/>La paranoia trumpiana hace recordar la de 12 horas para sobrevivir, en la que la poblaci\u00f3n dispon\u00eda de ese plazo, para asesinar a quien deseara.<br \/>Se trata del primer filme de MacGowan, quien hab\u00eda producido filmes como Bad dad o Back streets.<br \/>Aqu\u00ed no evita el gore, con violentas y sangrientas escenas, que no ser\u00e1n del agrado del grueso del p\u00fablico.<br \/>Red letter day resulta pues un fiel reflejo de la paranoia trumpiana, que hace creer que todo vecino es un enemigo en potencia.\u00a0\u00a0 <\/p>\n<p>Todo empeora, cuando Madison se entera de que debe matar a Luther, pero \u00e9ste se le adelanta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CINE DE HOY<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-89683","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/89683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=89683"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/89683\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=89683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=89683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=89683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}