{"id":88591,"date":"2019-08-07T06:41:10","date_gmt":"2019-08-07T06:41:10","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/08\/07\/heineken-green-challenge-iniciativa-para-cuidar-agua-2\/"},"modified":"2019-08-07T06:41:10","modified_gmt":"2019-08-07T06:41:10","slug":"heineken-green-challenge-iniciativa-para-cuidar-agua-2","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/heineken-green-challenge-iniciativa-para-cuidar-agua-2\/","title":{"rendered":"\u201cHeineken Green Challenge\u201d, iniciativa para cuidar agua"},"content":{"rendered":"<p>Mejoramiento del planeta\u00a0 \u00a0 <\/p>\n<p>  <!--more-->  <\/p>\n<p>Presentan la segunda edici\u00f3n del \u201cHeineken Green Challenge\u201d, iniciativa que busca emprendedores sociales con el objetivo de contribuir al mejoramiento del planeta, espec\u00edficamente en el cuidado del agua.\u2028\u2028Ricardo Pacheco, gerente de Heineken M\u00e9xico, zona Hidalgo, precis\u00f3 que para la empresa, \u201chablar de sustentabilidad y responsabilidad social corporativa es un compromiso vinculado en esencia a nuestra visi\u00f3n de negocio, ya que con estas acciones, contribuimos al desarrollo del pa\u00eds, alineados a nuestra estrategia global de sustentabilidad\u201d.\u00a0 \u2028\u2028Apunt\u00f3 que en el 2018 la compa\u00f1\u00eda tuvo una reducci\u00f3n de 30 por ciento del consumo de agua con respecto al 2010, y que la industria es referencia a nivel mundial con un gasto de solo dos punto seis litros, por litro de cerveza producido, lo cual la coloca en la posici\u00f3n n\u00famero uno en menor uso de l\u00edquido.<br \/>En esta segunda edici\u00f3n los premios ascienden a un mill\u00f3n 150 mil pesos, repartidos en 500 mil pesos para el primer lugar, 200 mil pesos para el segundo, 100 mil para el tercero, y 50 mil pesos del cuarto al d\u00e9cimo puesto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mejoramiento del planeta\u00a0 \u00a0<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-88591","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/88591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=88591"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/88591\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=88591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=88591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=88591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}