{"id":83891,"date":"2019-05-20T04:23:17","date_gmt":"2019-05-20T04:23:17","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/05\/20\/estalla-bomba-en-egipto-hay-16-heridos\/"},"modified":"2019-05-20T04:23:17","modified_gmt":"2019-05-20T04:23:17","slug":"estalla-bomba-en-egipto-hay-16-heridos","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/estalla-bomba-en-egipto-hay-16-heridos\/","title":{"rendered":"Estalla bomba en Egipto, hay 16 heridos"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0El ataque ocurri\u00f3 cerca de las pir\u00e1mides de Giza; es el segundo ataque en menos de seis meses\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>El Cairo.- Una bomba estall\u00f3 el domingo al paso de un autob\u00fas lleno de turistas cerca de las pir\u00e1mides de Giza en Egipto, hiriendo a 16 personas, informaron autoridades.<\/p>\n<p>Egipto ha estado librando una batalla contra extremistas en la Pen\u00ednsula del Sina\u00ed desde hace varios a\u00f1os y la insurgencia en ocasiones ha trascendido al territorio continental, especialmente impactando a la minor\u00eda cristiana o a turistas extranjeros. <\/p>\n<p>El ataque surge en momentos en que la industria tur\u00edstica del pa\u00eds parec\u00eda estar recuper\u00e1ndose tras ser afectada por la inestabilidad pol\u00edtica que sigui\u00f3 al derrocamiento en el 2011 del entonces presidente Hosni Mubarak. Es el segundo ataque contra las pir\u00e1mides en menos de seis meses.<\/p>\n<p>As\u00ed mismo, se indic\u00f3 que todas las fuentes entrevistadas, hablaron a condici\u00f3n de anonimato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0El ataque ocurri\u00f3 cerca de las pir\u00e1mides de Giza; es el segundo ataque en menos de seis meses\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-83891","post","type-post","status-publish","format-standard","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=83891"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83891\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=83891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=83891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=83891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}