{"id":83890,"date":"2019-05-20T04:22:46","date_gmt":"2019-05-20T04:22:46","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/05\/20\/esperan-hasta-24-horas-para-cargar-combustible\/"},"modified":"2019-05-20T04:22:46","modified_gmt":"2019-05-20T04:22:46","slug":"esperan-hasta-24-horas-para-cargar-combustible","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/esperan-hasta-24-horas-para-cargar-combustible\/","title":{"rendered":"Esperan hasta 24 horas para cargar combustible"},"content":{"rendered":"<p>En Venezuela <br \/>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Un sat\u00e9lite captur\u00f3 im\u00e1genes de autos a lo largo de 1.6 kil\u00f3metros a trav\u00e9s de Maracaibo hasta las estaciones de servicio; \u201ctengo cuatro d\u00edas intentando surtir gasolina y no he podido\u201d, dijo una doctora\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Las sanciones estadounidenses contra la industria petrolera venezolana parecen estar surtiendo efecto, y han comenzado a verse largas colas de personas en las gasolineras de Maracaibo, la segunda mayor ciudad del pa\u00eds sudamericano<\/p>\n<p>Con el tanque casi vac\u00edo y atascado en la la, la doctora en enfermedades infecciosas Yoli Urdaneta coment\u00f3 que no ha podido cumplir con su turno para tratar a los pacientes. &#8220;Tengo cuatro d\u00edas intentando surtir gasolina y no he podido&#8221;, se lament\u00f3.<\/p>\n<p>Un sat\u00e9lite que cruz\u00f3 Maracaibo el jueves captur\u00f3 im\u00e1genes de autos en la a lo largo de 1.6 kil\u00f3metros a trav\u00e9s de la ciudad hasta las estaciones de servicio, seg\u00fan Maxar Technologies, una compa\u00f1\u00eda de tecnolog\u00eda espacial con sede en Estados Unidos. Russ Dallen, de la empresa nanciera Caracas Capital Markets, ubicada en Miami, declar\u00f3 el domingo que las severas sanciones de Washington, m\u00e1s all\u00e1 del deterioro de las refiner\u00edas, han comenzado a afectar al mercado dom\u00e9stico. Venezuela no tiene el efectivo para importar insumos claves que le permitan mantener la producci\u00f3n, a pesar de que tiene las reservas de crudo m\u00e1s grandes del mundo, dijo Dallen, quien estim\u00f3 que la petrolera estatal Petr\u00f3leos de Venezuela S.A. (PDVSA) est\u00e1 produciendo a entre el 10 y el 15% de su capacidad.<\/p>\n<p>La producci\u00f3n petrolera venezolana ya estaba en declive incluso antes de las sanciones estadounidenses recientes. Pero Dallen estima que las medidas ahora est\u00e1n empezando a tener efectos reales, y que las refiner\u00edas venezolanas est\u00e1n operando muy por debajo de su capacidad debido a la falta de mantenimiento. <\/p>\n<p>El gobierno del presidente estadounidense Donald Trump sancion\u00f3 a PDVSA en un esfuerzo por expulsar al presidente Nicol\u00e1s Maduro de su cargo, al tiempo que brind\u00f3 su apoyo al l\u00edder opositor Juan Guaid\u00f3. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Venezuela \u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Un sat\u00e9lite captur\u00f3 im\u00e1genes de autos a lo largo de 1.6 kil\u00f3metros a trav\u00e9s de Maracaibo hasta las estaciones de servicio; \u201ctengo cuatro d\u00edas intentando surtir gasolina y no he podido\u201d, dijo una doctora\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-83890","post","type-post","status-publish","format-standard","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=83890"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83890\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=83890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=83890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=83890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}