{"id":83022,"date":"2019-05-06T04:16:31","date_gmt":"2019-05-06T04:16:31","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/05\/06\/ingresa-nuevo-director-para-reforzar-al-organismo-operador\/"},"modified":"2019-05-06T04:16:31","modified_gmt":"2019-05-06T04:16:31","slug":"ingresa-nuevo-director-para-reforzar-al-organismo-operador","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/ingresa-nuevo-director-para-reforzar-al-organismo-operador\/","title":{"rendered":"Ingresa nuevo director para reforzar al Organismo operador"},"content":{"rendered":"<p>CAMBIO EN CAAMT<\/p>\n<p>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Asegura alcalde que el ex director, Arturo Ruiz, es un t\u00e9cnico con amplio conocimiento que debe estar en campo \u00a0\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>El ingreso de Rodolfo Pascoe al frente de la Comisi\u00f3n de Agua y Alcantarillado del municipio de Tulancingo (CAAMT) obedece a un asunto de \u201crefuerzo de capacidades\u201d, ya que el ex director, Arturo Ruiz, es un t\u00e9cnico con amplio conocimiento que debe estar laborando en campo.<br \/>\u201cTengo a un director t\u00e9cnico, el m\u00e1s capacitado y el que tiene m\u00e1s conocimiento de la red de infraestructura hidr\u00e1ulica que se llama Arturo Ruiz, y que debe estar en el campo vigilando las brigadas de atenci\u00f3n\u201d, destac\u00f3 el mandatario.<br \/>Agreg\u00f3 que este organismo operador cuenta tambi\u00e9n con Nancy Lorena Mac\u00edas, quien est\u00e1 a cargo del \u00e1rea de finanzas, y a este equipo se suma Rodolfo Pascoe como director general, para escuchar y brindar la atenci\u00f3n ciudadana.<br \/>\u201cTiene la experiencia, fue alguna vez director de la Comisi\u00f3n de Agua; sabe de lo que habla, no es una persona improvisada, es un hombre capaz, y conjuntamente con Eduardo Romero Batalla le van a dar a la gente esa atenci\u00f3n\u201d, concluy\u00f3.<br \/>Rodolfo Pascoe, quien fue presentado el pasado lunes 22 de abril al frente del organismo operador, tuvo este mismo cargo en la administraci\u00f3n del ex presidente Julio Soto M\u00e1rquez, del 2012 a diciembre del 2014 y fue sustituido por Guillermo L\u00f3pez. <br \/>En aquel entonces, se manej\u00f3 que su salida se debi\u00f3 a motivos personales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAMBIO EN CAAMT \u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Asegura alcalde que el ex director, Arturo Ruiz, es un t\u00e9cnico con amplio conocimiento que debe estar en campo \u00a0\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-83022","post","type-post","status-publish","format-standard","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=83022"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83022\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=83022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=83022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=83022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}