{"id":83021,"date":"2019-05-06T04:16:30","date_gmt":"2019-05-06T04:16:30","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/05\/06\/suman-95-incendios-forestales\/"},"modified":"2019-05-06T04:16:30","modified_gmt":"2019-05-06T04:16:30","slug":"suman-95-incendios-forestales","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/suman-95-incendios-forestales\/","title":{"rendered":"Suman 95 incendios forestales"},"content":{"rendered":"<p>HIDALGO <br \/>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0El estado est\u00e1 en el noveno lugar nacional en superficie afectada\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>De acuerdo con informaci\u00f3n de la Comisi\u00f3n Nacional Forestal (Conafor), del primero de enero y hasta el pasado 2 de mayo, Hidalgo suma un total de 95 incendios forestales, con una afectaci\u00f3n de 942.30 hect\u00e1reas.<br \/>En tanto, con base en el reporte semanal que comprende del 26 de abril al 2 de mayo, a nivel nacional se presentaron 181 siniestros en 17 entidades federativas, afectando un total de ocho mil 348.33 hect\u00e1reas. <br \/>De esta superficie, el 93.72 por ciento correspondi\u00f3 a vegetaci\u00f3n en los estratos herb\u00e1ceo y arbustivo y el 6.28 al arb\u00f3reo; siendo las entidades federativas m\u00e1s afectadas: San Luis Potos\u00ed, M\u00e9xico, Chihuahua, Quintana Roo y Zacatecas, que representan el 86.34 por ciento del total de la semana.<br \/>Espec\u00edficamente en el caso de Hidalgo, durante esta semana se registraron seis incendios forestales que afectaron un total de 76.4 hect\u00e1reas, cinco de ellas corresponden a la categor\u00eda de herb\u00e1ceo, 26 de arbolado adulto, 2.45 de renuevo y 42.95 de arbustos.<br \/>En este reporte semanal la entidad se encuentra fuera de las estad\u00edsticas de los 10 estados con mayor n\u00famero de incendios; sin embargo se encuentra en el n\u00famero 9 con mayor superficie afectada.<br \/>Asimismo, es importante se\u00f1alar que en el documento enlistan las causas de los siniestros, siendo el primer lugar los provocados intencionalmente con 30 por ciento, seguido de actividades agr\u00edcolas con 22, fogatas 12, actividades pecuarias 11, adem\u00e1s el 10 por ciento corresponde a causas desconocidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HIDALGO \u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0El estado est\u00e1 en el noveno lugar nacional en superficie afectada\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-83021","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=83021"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/83021\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=83021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=83021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=83021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}