{"id":82964,"date":"2019-05-05T14:49:04","date_gmt":"2019-05-05T14:49:04","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/05\/05\/exhortan-a-evitar-golpes-de-calor\/"},"modified":"2019-05-05T14:49:04","modified_gmt":"2019-05-05T14:49:04","slug":"exhortan-a-evitar-golpes-de-calor","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/exhortan-a-evitar-golpes-de-calor\/","title":{"rendered":"Exhortan a evitar golpes de calor"},"content":{"rendered":"<p>Continuar\u00e1n las altas temperaturas<\/p>\n<p>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Piden mandar a los ni\u00f1os a sus escuelas con una botella de agua, para hidratarse constantemente\u2028<br \/>Exhortan tambi\u00e9n a evitar consumir alimentos en la calle ya que el calor los descompone r\u00e1pidamente<\/p>\n<p>  <!--more-->  <\/p>\n<p>Debido a las altas temperaturas que se han presentado en la regi\u00f3n, el Centro de Salud exhort\u00f3 a las madres de familia a mandar a sus peque\u00f1os a la escuela con una botella de agua, para que constantemente se est\u00e9n hidratando. Mencionaron que es importante no exponerse a los rayos del sol y ponerse en el cuerpo y cara alg\u00fan protector solar para evitar da\u00f1os en la piel.<br \/>Argumentaron que continuamente se mantienen brindando atenci\u00f3n a la ciudadan\u00eda y ofreciendo orientaciones a todos aquellos que lo requieran, pues un golpe de calor es un tema delicado de tratar y con estas temperaturas se deben tener cuidados especiales. <br \/>Recomiendan tomar mucha agua embotellada, hervida o desinfectada, exhortan tambi\u00e9n a evitar consumir alimentos en la calle ya que el calor los descompone r\u00e1pidamente y puede provocar enfermedades estomacales o de otro tipo, recomiendan no exponerse al sol especialmente entre las 11:00 horas y las 15:00 horas, tiempo en el que los rayos del sol est\u00e1n con toda su intensidad y es m\u00e1s da\u00f1ino para la piel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuar\u00e1n las altas temperaturas \u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Piden mandar a los ni\u00f1os a sus escuelas con una botella de agua, para hidratarse constantemente\u2028Exhortan tambi\u00e9n a evitar consumir alimentos en la calle ya que el calor los descompone r\u00e1pidamente<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-82964","post","type-post","status-publish","format-standard","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/82964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=82964"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/82964\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=82964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=82964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=82964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}