{"id":81767,"date":"2019-04-12T04:37:22","date_gmt":"2019-04-12T04:37:22","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/04\/12\/detiene-policia-britanica-al-fundador-de-wikileaks\/"},"modified":"2019-04-12T04:37:22","modified_gmt":"2019-04-12T04:37:22","slug":"detiene-policia-britanica-al-fundador-de-wikileaks","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/detiene-policia-britanica-al-fundador-de-wikileaks\/","title":{"rendered":"Detiene polic\u00eda brit\u00e1nica al fundador de WikiLeaks"},"content":{"rendered":"<p>El derechista Len\u00edn Moreno le retir\u00f3 la inmunidad diplom\u00e1tica <\/p>\n<p>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0La polic\u00eda metropolitana fue invitada a la embajada despu\u00e9s de la retirada del asilo\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Julian Assange, refugiado desde 2012 en la embajada de Ecuador en Londres, fue detenido ayer por la polic\u00eda brit\u00e1nica despu\u00e9s de que Quito le retirara el asilo diplom\u00e1tico, inform\u00f3 Scotland Yard en un comunicado. <br \/>&#8220;La polic\u00eda metropolitana fue invitada a la embajada por el embajador (de Ecuador) despu\u00e9s de la retirada del asilo por el gobierno ecuatoriano&#8221;, se\u00f1al\u00f3 la polic\u00eda londinense. <br \/>Assange, de 47 a\u00f1os, fue trasladado &#8220;a una comisar\u00eda del centro de Londres donde permanecer\u00e1 hasta que comparezca ante un juez cuanto antes&#8221;, agreg\u00f3 el comunicado. <br \/>La televisi\u00f3n mostr\u00f3 como agentes de la polic\u00eda de Londres sacaban a Assange, con larga barba blanca, a rastras del edificio de la embajada ecuatoriana, donde entr\u00f3 el 19 de junio de 2012 para escapar a una extradici\u00f3n a Suecia. <br \/>La plataforma de difusi\u00f3n de documentos secretos WikiLeaks, llevaba d\u00edas advirtiendo que el presidente ecuatoriano Len\u00edn Moreno se dispon\u00eda a retirar a Assange la protecci\u00f3n diplom\u00e1tica que le dio su predecesor Rafael Correa. <br \/>WikiLeaks denunci\u00f3 la decisi\u00f3n de Quito como &#8220;ilegal&#8221; y &#8220;en violaci\u00f3n del derecho internacional&#8221;. <br \/>&#8220;Len\u00edn Moreno, nefasto presidente del Ecuador, ha demostrado su miseria humana al mundo, entregando a Juli\u00e1n Assange -no solo asilado, sino tambi\u00e9n ciudadano ecuatoriano- a la polic\u00eda brit\u00e1nica&#8221;, tuite\u00f3 por su parte Rafael Correa, que ahora vive asilado en B\u00e9lgica. &#8220;Esto pone en riesgo la vida de Assange, y humilla al Ecuador. D\u00eda de luto mundial&#8221;, agreg\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El derechista Len\u00edn Moreno le retir\u00f3 la inmunidad diplom\u00e1tica \u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0La polic\u00eda metropolitana fue invitada a la embajada despu\u00e9s de la retirada del asilo\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-81767","post","type-post","status-publish","format-standard","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/81767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=81767"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/81767\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=81767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=81767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=81767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}