{"id":78401,"date":"2019-02-05T11:24:18","date_gmt":"2019-02-05T11:24:18","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/02\/05\/alcalde-inaugura-drenaje-sanitario-en-calle-de-la-comunidad-de-el-huaxtho\/"},"modified":"2019-02-05T11:24:18","modified_gmt":"2019-02-05T11:24:18","slug":"alcalde-inaugura-drenaje-sanitario-en-calle-de-la-comunidad-de-el-huaxtho","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/alcalde-inaugura-drenaje-sanitario-en-calle-de-la-comunidad-de-el-huaxtho\/","title":{"rendered":"Alcalde inaugura drenaje sanitario en   calle de la comunidad de El Huaxth\u00f3"},"content":{"rendered":"<p>Actopan<br \/>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Hace un repaso del Actopan que tom\u00f3 hace casi tres a\u00f1os, al Actopan actual \u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Actualmente, en el municipio de Actopan existe mayor n\u00famero de habitantes con acceso a servicios b\u00e1sicos como es el agua potable, drenaje, electricidad, incluso caminos. <br \/>Lo dijo el presidente municipal H\u00e9ctor Cruz Olgu\u00edn al recordar que uno de los objetivos de la presente administraci\u00f3n municipal es abatir el rezago social. <br \/>\u201cQue los ciudadanos tengan piso parejo en todo el municipio, las condiciones m\u00ednimas de dignidad para vivir\u201d, sostuvo el mandatario municipal durante la inauguraci\u00f3n del drenaje sanitario en la calle Pirales en la comunidad de El Huaxth\u00f3.<br \/>Hace dos a\u00f1os, casi tres, el alcalde tom\u00f3 protesta de su cargo p\u00fablico y en ese entonces confes\u00f3 la existencia de una gran cantidad de actopenses carentes de los servicios p\u00fablicos indispensables para tener una vida digna. <br \/>\u201cEncontr\u00e9 que en comunidades y colonias, exist\u00edan a\u00fan atrasos sociales muy importantes, familias que no pod\u00edan acceder a servicios como el agua potable, el drenaje, la luz el\u00e9ctrica o caminos. <br \/>Entonces se hizo el planteamiento, que para permitir que el municipio realmente avance, se ten\u00edan que generar las condiciones m\u00ednimas a las familias, particularmente las que menos posibilidades ten\u00edan de contar servicios b\u00e1sicos\u201d, expres\u00f3 ante vecinos y autoridades presentes.<br \/>Refiri\u00f3 en su mensaje con respecto a la comunidad El Huaxth\u00f3, se le han invertido recursos por m\u00e1s de cinco millones de pesos, en obras de electrificaci\u00f3n, drenajes sanitarios, pavimentaciones, cuartos dormitorios, entre otras.<br \/>\u201cAlgo que s\u00ed les puedo decir, que estamos comprometidos con hacer justicia social, con poner el piso parejo para todos, que las familias cuenten m\u00ednimamente con los servicios para tener una vida digna\u201d.<br \/>Hoy, dijo, m\u00e1s familias pueden en sus casas abrir la llave y tener agua potable, o tener un sanitario que est\u00e1 conectado al sistema de drenaje o bien contar con aparatos electrodom\u00e9sticos, todo eso sostuvo, se traduce en una cosa, mejores condiciones de vida.<br \/>Por \u00faltimo Cruz Olgu\u00edn subray\u00f3 que mantendr\u00e1 una pol\u00edtica de austeridad, asimismo de dirigir los recursos a resarcir los rezagos que a\u00fan siguen presentes en las colonias y comunidades. Reconoci\u00f3, que las necesidades no se terminan, pero se comprometi\u00f3 a gestionar recursos para atenderlas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actopan\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Hace un repaso del Actopan que tom\u00f3 hace casi tres a\u00f1os, al Actopan actual \u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-78401","post","type-post","status-publish","format-standard","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/78401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=78401"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/78401\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=78401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=78401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=78401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}