{"id":77362,"date":"2019-01-15T14:58:56","date_gmt":"2019-01-15T14:58:56","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/01\/15\/subastaran-acuarela-del-pintor-mexicano-saturnino-herran\/"},"modified":"2019-01-15T14:58:56","modified_gmt":"2019-01-15T14:58:56","slug":"subastaran-acuarela-del-pintor-mexicano-saturnino-herran","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/subastaran-acuarela-del-pintor-mexicano-saturnino-herran\/","title":{"rendered":"Subastar\u00e1n acuarela del pintor mexicano Saturnino Herr\u00e1n"},"content":{"rendered":"<p>Se trata de una delicada acuarela y gouche sobre papel con estimados de 60 mil y 80 mil pesos creada en 1912<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una acuarela fechada en 1912 del pintor mexicano Saturnino Herr\u00e1n ser\u00e1 subastada el pr\u00f3ximo 17 de enero en la Ciudad de M\u00e9xico.<br \/>Se trata de una delicada acuarela y gouche sobre papel de 7.5&#215;12.5 cent\u00edmetros, con estimados de 60 mil y 80 mil pesos, detall\u00f3 la casa de subastas Morton.<br \/>La obra, que fue pintada cuatro a\u00f1os antes de la prematura muerte del artista a los 31 a\u00f1os, sirvi\u00f3 de dise\u00f1o para el n\u00famero de A\u00f1o Nuevo de La Revista de Revistas \/ Semanario Nacional, creado por un grupo de intelectuales de Guadalajara en 1910 con el objetivo de integrar contenidos para un p\u00fablico variado.<br \/>Considerado uno de los precursores del muralismo en M\u00e9xico. Saturnino Herr\u00e1n retrat\u00f3 la mexicanidad en su vida cotidiana y su trabajo ha sido una gran influencia en la escuela mexicana; actualmente sus obras se pueden apreciar en el Museo Nacional de Arte en la muestra Saturnino Herr\u00e1n y otros modernistas.<br \/>La acuarela ser\u00e1 expuesta en el lugar de la subasta, junto con una importante selecci\u00f3n de pintura y escultura mexicana y europea, piezas de plata, porcelana, charerr\u00eda, mobiliario europeo, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de una delicada acuarela y gouche sobre papel con estimados de 60 mil y 80 mil pesos creada en 1912<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-77362","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/77362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=77362"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/77362\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=77362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=77362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=77362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}