{"id":77306,"date":"2019-01-14T14:57:12","date_gmt":"2019-01-14T14:57:12","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2019\/01\/14\/reparte-amlo-cartilla-de-valores\/"},"modified":"2019-01-14T14:57:12","modified_gmt":"2019-01-14T14:57:12","slug":"reparte-amlo-cartilla-de-valores","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/reparte-amlo-cartilla-de-valores\/","title":{"rendered":"Reparte AMLO cartilla de valores"},"content":{"rendered":"<p>Bajo Reserva Expr\u00e9s<\/p>\n<p>  <!--more-->  <\/p>\n<p>A partir de hoy, el gobierno federal comenz\u00f3 a repartir entre la poblaci\u00f3n la cartilla moral de Alfonso Reyes que contiene una serie valores \u00e9ticos y morales.<br \/>Nos comentan que el gobierno imprimi\u00f3 10 mil ejemplares en la Comisi\u00f3n Nacional de Libros de Texto Gratuitos y es repartida en los eventos oficiales del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.<br \/>Nos adelantan que este peque\u00f1o texto ser\u00e1 la base para la constituci\u00f3n moral que realiza el mandatario nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo Reserva Expr\u00e9s<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-77306","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/77306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=77306"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/77306\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=77306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=77306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=77306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}