{"id":69094,"date":"2018-08-21T11:33:35","date_gmt":"2018-08-21T11:33:35","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2018\/08\/21\/se-llevara-el-tren-a-la-promocion-turistica\/"},"modified":"2018-08-21T11:33:35","modified_gmt":"2018-08-21T11:33:35","slug":"se-llevara-el-tren-a-la-promocion-turistica","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/se-llevara-el-tren-a-la-promocion-turistica\/","title":{"rendered":"\u00bfSe llevar\u00e1 el tren a la promoci\u00f3n tur\u00edstica?"},"content":{"rendered":"<p>En Clave Tur\u00edstica<br \/>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Conviene recordar que el origen de este mecanismo y del Impuesto sobre servicios de hospedaje, se remonta a los a\u00f1os 90 del siglo pasado, en que se present\u00f3 una crisis en la disponibilidad de recursos p\u00fablicos para estos prop\u00f3sitos de promoci\u00f3n\u2028<br \/>\u00a0<\/p>\n<p>  <!--more-->  <\/p>\n<p>Hace un par de semanas, en este mismo espacio, advert\u00edamos de los riesgos sobre el financiamiento a la promoci\u00f3n tur\u00edstica del pa\u00eds ejecutada a trav\u00e9s del Consejo de Promoci\u00f3n Tur\u00edstica de M\u00e9xico (CPTM), luego de que se present\u00f3 una iniciativa en el Congreso para reducir su participaci\u00f3n en la distribuci\u00f3n de la bolsa recabada a trav\u00e9s del Derecho de No Residente (DNR). <br \/>Conviene recordar que el origen de este mecanismo y del Impuesto sobre servicios de hospedaje, se remonta a los a\u00f1os 90 del siglo pasado, en que se present\u00f3 una crisis en la disponibilidad de recursos p\u00fablicos para estos prop\u00f3sitos de promoci\u00f3n; de igual manera, es por dem\u00e1s pertinente subrayar que la introducci\u00f3n de estas cargas fiscales surgi\u00f3 en acuerdo con la iniciativa privada pues ambas modalidades supusieron impactos en las tarifas pagadas por los turistas, poniendo en peligro la competitividad de empresas y destinos.<br \/>As\u00ed las cosas, la semana pasada, al dar a conocer el equipo de trabajo en turismo, el nuevo Gobierno inform\u00f3 de la ampliaci\u00f3n de la cobertura del &#8220;tren maya&#8221; que ahora incluir\u00eda Tabasco, Yucat\u00e1n y Campeche (en la parte norte), adem\u00e1s del previamente anunciado trayecto de Canc\u00fan a Palenque, pasando por Tulum, Bacalar y Calakmul. <br \/>Para financiar esta obra se recurrir\u00eda, al menos en parte, a los fondos del &#8220;impuesto al turismo&#8221; estimados en 7 mil millones de pesos anuales.<br \/>M\u00e1s all\u00e1 de la necesidad de contar con informaci\u00f3n detallada de la obra ferroviaria, particularmente en lo que se refiere a su viabilidad desde el punto de vista del mercado y la fragilidad ambiental de algunas de estas zonas del pa\u00eds, y considerando al menos a priori que puede ser factible el tramo entre Canc\u00fan y Tulum, por el volumen de turistas y de la propia poblaci\u00f3n local que se desplaza en este corredor, existe una gran preocupaci\u00f3n entre los representantes empresariales del sector tur\u00edstico, pues la obligada lectura apunta a interpretar que el &#8220;impuesto al turismo&#8221; es, ni m\u00e1s ni menos que el mencionado DNR, lo que supondr\u00eda \u2014ante la falta de m\u00e1s informaci\u00f3n\u2014 que el CPTM (que hoy dispone de 70% de la recaudaci\u00f3n de dicho derecho) se quedar\u00eda sin los recursos para realizar sus tareas sustantivas.<br \/>Si lo anterior llegara a consumarse, la impresi\u00f3n es que se estar\u00eda poniendo en riesgo de manera significativa la presencia de M\u00e9xico en los mercados tur\u00edsticos internacionales, pues no parece probable que el esfuerzo individual de las empresas mexicanas sea capaz de sobrellevar una dura competencia por los turistas, en mercados en donde las inversiones en mercadotecnia por parte de pa\u00edses, destinos y las propias firmas empresariales en ellos asentados, son enormes. <br \/>As\u00ed, por ejemplo, el presupuesto anual de la Oficina de Visitantes y Convenciones de Las Vegas supera los 300 millones de d\u00f3lares; por su parte, Orlando ejercer\u00e1 en este a\u00f1o unos 87 millones de d\u00f3lares en acciones de mercadotecnia tur\u00edstica, adem\u00e1s de los poco m\u00e1s de 76 millones de d\u00f3lares de presupuesto p\u00fablico para la promoci\u00f3n tur\u00edstica de Florida, importes a los que habr\u00eda que adicionar unos 30 millones de d\u00f3lares de impuestos para el fondeo de la Oficina de Visitantes y Convenciones de Miami.<br \/>A este escenario habr\u00eda que agregar la realidad de que el ciclo de expansi\u00f3n de la demanda internacional al pa\u00eds, de acuerdo con la informaci\u00f3n p\u00fablica disponible parece sufrir una desaceleraci\u00f3n, pues luego de los niveles de crecimiento en torno a dos d\u00edgitos registrados en los \u00faltimos a\u00f1os, ahora se reporta que el aumento en los ingresos por turistas no fronterizos es de 3.5% y el de los turistas provenientes de Estados Unidos por v\u00eda a\u00e9rea al pa\u00eds, es de s\u00f3lo 1.2% en los primeros seis meses del a\u00f1o.<br \/>Por tanto y reconociendo que la labor de promoci\u00f3n tur\u00edstica del pa\u00eds puede realizarse con mayor eficiencia, eficacia, transparencia y una mejor rendici\u00f3n de cuentas, producto de la evaluaci\u00f3n adecuada de las campa\u00f1as promocionales, parece necesario que se aclare qu\u00e9 es lo que va a pasar con el CPTM y, sobre todo, como es que se compensar\u00eda (de ser el caso, ante lo aqu\u00ed expuesto) la canalizaci\u00f3n de los recursos para la promoci\u00f3n tur\u00edstica de M\u00e9xico, recordando que de presentarse una ca\u00edda en los flujos tur\u00edsticos al pa\u00eds, no s\u00f3lo supondr\u00eda una afectaci\u00f3n para las empresas, sino tambi\u00e9n para la captaci\u00f3n fiscal, adem\u00e1s de propiciar una p\u00e9rdida de empleos y, como consecuencia de estas y otras afectaciones, se producir\u00eda un impacto significativo para el desarrollo del pa\u00eds.<br \/>\u00a0<br \/>Twitter: @fcomadrid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Clave Tur\u00edstica\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Conviene recordar que el origen de este mecanismo y del Impuesto sobre servicios de hospedaje, se remonta a los a\u00f1os 90 del siglo pasado, en que se present\u00f3 una crisis en la disponibilidad de recursos p\u00fablicos para estos prop\u00f3sitos de promoci\u00f3n\u2028\u00a0<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-69094","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/69094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=69094"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/69094\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=69094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=69094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=69094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}