{"id":64180,"date":"2018-05-28T12:19:11","date_gmt":"2018-05-28T12:19:11","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2018\/05\/28\/las-inevitables-ausencias-2\/"},"modified":"2018-05-28T12:19:11","modified_gmt":"2018-05-28T12:19:11","slug":"las-inevitables-ausencias-2","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/las-inevitables-ausencias-2\/","title":{"rendered":"Las inevitables ausencias"},"content":{"rendered":"<p>FAMILIA POL\u00cdTICA<br \/>\u00a0<br \/>\u00a0\u00a0\u00a0 \u00a0Muchos de mis amigos del alma y familiares ya murieron (no los menciono, por el riesgo de una omisi\u00f3n).\u00a0\u00a0Otra vez, confieso que no los extra\u00f1o: aunque sea mentira piadosa o ganas de creer, hago como si anduvieran de viaje y alg\u00fan d\u00eda pudiera darse el reencuentro; tal vez extra\u00f1o pero \u00bfImposible?<br \/>\u00a0<br \/>Para mi hermano: Profesor Jaime Ibarra Chavarr\u00eda (Q.E.P.D.)<br \/>\u00a0<\/p>\n<p>  <!--more-->  <\/p>\n<p>Cada d\u00eda se hace m\u00e1s corta la fila ante la ventanilla simb\u00f3lica donde se refrendan los boletos que al nacer todos compramos para partir con rumbo a lo desconocido.\u00a0\u00a0Los nombres de amigos muertos crece, aunque los verbos vivir y convivir se sigan conjugando en presente por quienes aqu\u00ed quedamos.\u00a0\u00a0Aunque parezca inhumano, yo no extra\u00f1o a mis amigos cuando se\u00a0\u00a0van, los recuerdo actuales, como si anduvieran de viaje y alg\u00fan d\u00eda podamos volver a vernos.<br \/>\u00a0\u00a0\u00a0 \u00a0No tengo valor para mirar a un cad\u00e1ver en su f\u00e9retro (ni siquiera los de mis padres), quiero borrar de mi memoria todo rictus de muerte y hacer de su rostro sereno mi compa\u00f1ero de cotidiano amor, gratitud y protecci\u00f3n.<br \/>\u00a0\u00a0\u00a0 \u00a0Ni la l\u00f3gica ni la cronolog\u00eda pueden predecir la trayectoria de la fatal guada\u00f1a, menos a\u00fan la identidad de sus destinatarios.\u00a0\u00a0Por ejemplo, hay ancianos, casi centenarios: desahuciados, solos, sin amor, sin atenciones, sin recuerdos\u2026 que viven sin vivir; est\u00e1n aqu\u00ed, a\u00fan en contra de su voluntad.\u00a0\u00a0\u00a1Qu\u00e9 lejos se ve la posibilidad de una muerte voluntaria!<br \/>\u00a0\u00a0\u00a0 \u00a0Cu\u00e1ntos se van cuando a\u00fan no es tiempo, de acuerdo con los par\u00e1metros mortales: ni\u00f1os, j\u00f3venes, adultos en plenitud de facultades, seres humanos cuya mejor parte queda por vivir\u2026\u00a0\u00a0Dejan profundas huellas de dolor y da\u00f1o en sus seres queridos.<br \/>\u00a0\u00a0\u00a0 \u00a0Las historias de infancia son tambi\u00e9n destino: chiquillos que nacen y dejan de respirar con escasos minutos de diferencia, otros (como los c\u00e9lebres biafranos) encuentran un mundo sin oportunidades; son v\u00edctimas de inanici\u00f3n temprana y casi siempre inevitable.<br \/>En ruidosas calles de las grandes ciudades, hay rincones de soledad en d\u00f3nde viven y mueren peque\u00f1os seres en el infierno de los abusos y los malos tratos: drogas, explotaci\u00f3n, prostituci\u00f3n, tr\u00e1fico de \u00f3rganos\u2026<br \/>En nuestro M\u00e9xico, miles de adolescentes, reniegan de su circunstancia que los condena a la miseria, aspiran a salir de ella y se inspiran en narcocorridos, pel\u00edculas, leyendas\u2026\u00a0\u00a0Adoptan como arquetipos a c\u00e9lebres traficantes, secuestradores y otros ejemplares de fauna nociva; algunos (as) hasta pretenden llegar al Congreso bajo la sombra de \u201cya sabes qui\u00e9n\u201d.\u00a0 <br \/>A la manera de Pancho L\u00f3pez (personaje de una canci\u00f3n de Miguel Aceves Mej\u00eda): \u201cViven la vida con mucha rapidez\u201d: inconformes eternos, alg\u00fan d\u00eda se encuentran con poderosos padrinos, quienes, antes de terminar en la c\u00e1rcel o en el pante\u00f3n, los explotan, los transforman en viciosos y asesinos, les dan dinero, hasta que conquistan su \u00faltimo trofeo: un lugar an\u00f3nimo en la fosa com\u00fan, en el \u00e1cido de un \u201cpozolero\u201d o en las repugnantes entra\u00f1as de los buitres.<br \/>Los muertos en general y mis amigos en particular me dan envidia, cuando parten sin largos periodos de agon\u00eda, despu\u00e9s de ver que sus hijos crecen (algunos hasta triunfan) y hacen de sus nietos motivos de postrera adoraci\u00f3n.\u00a0\u00a0Al principio se nota su ausencia, despu\u00e9s se hace costumbre.<br \/>\u00a0\u00a0\u00a0 \u00a0Me da terror enfrentar la dolorosa rutina de permanecer durante mucho tiempo postrado en una cama: vegetar en terapia intensiva conectado a ductos de vida artificial; con la faz cadav\u00e9rica, existiendo, sin vivir, d\u00edas que no dejan huella y lo peor\u2026 sin clara conciencia de que un d\u00eda vendr\u00e1 la liberaci\u00f3n.\u00a0\u00a0Un personaje de Taylor Caldwell defin\u00eda al infierno al decir que en \u00e9l \u201chay tiempo, pero no hay futuro\u201d.<br \/>\u00a0\u00a0\u00a0 \u00a0Reitero: creo que no temo a la muerte, pero s\u00ed al proceso anterior a ella.\u00a0\u00a0La visi\u00f3n de una mejor dimensi\u00f3n (ayer negada) se fortalece con los a\u00f1os.\u00a0\u00a0El miedo a La Nada se transforma en esperanza.<br \/>\u00a0\u00a0\u00a0 \u00a0Por herencia, algunos tenemos expectativas de una larga vida.\u00a0\u00a0Esa longevidad potencial (\u00bfbendici\u00f3n o maldici\u00f3n?) se lleva sin m\u00e1s alternativas que la resignaci\u00f3n o el suicidio (aunque lo ideal ser\u00eda irse como en una escena de la pel\u00edcula Cuando el destino nos alcance o en la ut\u00f3pica c\u00e1mara que para morir felices, los soberanos ten\u00edan en la Atl\u00e1ntida de Caldwell).<br \/>\u00a0\u00a0\u00a0 \u00a0Muchos de mis amigos del alma y familiares ya murieron (no los menciono, por el riesgo de una omisi\u00f3n).\u00a0\u00a0Otra vez, confieso que no los extra\u00f1o: aunque sea mentira piadosa o ganas de creer, hago como si anduvieran de viaje y alg\u00fan d\u00eda pudiera darse el reencuentro; tal vez extra\u00f1o pero \u00bfImposible?<br \/>\u00a0\u00a0\u00a0 \u00a0Hoy procuro disfrutar la compa\u00f1\u00eda de selectos amigos de toda la vida, en torno a alegre mesa de caf\u00e9.\u00a0\u00a0A estas alturas creo que estamos m\u00e1s all\u00e1 del bien y del mal; dif\u00edcilmente las humanas diferencias podr\u00edan separarnos.\u00a0\u00a0S\u00f3lo la ineluctable guada\u00f1a de Tanatos.\u00a0\u00a0\u00bfCu\u00e1ndo ser\u00e1?<br \/>Mayo, 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FAMILIA POL\u00cdTICA\u00a0\u00a0\u00a0\u00a0 \u00a0Muchos de mis amigos del alma y familiares ya murieron (no los menciono, por el riesgo de una omisi\u00f3n).\u00a0\u00a0Otra vez, confieso que no los extra\u00f1o: aunque sea mentira piadosa o ganas de creer, hago como si anduvieran de viaje y alg\u00fan d\u00eda pudiera darse el reencuentro; tal vez extra\u00f1o pero \u00bfImposible?\u00a0Para mi hermano: [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-64180","post","type-post","status-publish","format-standard","hentry","category-prisciliano-gutierrez"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/64180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=64180"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/64180\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=64180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=64180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=64180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}