{"id":64177,"date":"2018-05-28T12:16:23","date_gmt":"2018-05-28T12:16:23","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2018\/05\/28\/alfil-negro-1213\/"},"modified":"2018-05-28T12:16:23","modified_gmt":"2018-05-28T12:16:23","slug":"alfil-negro-1213","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/alfil-negro-1213\/","title":{"rendered":"ALFIL NEGRO"},"content":{"rendered":"<p>LA ESTRATEGIA DE GODOS<br \/>MEJOR QUE LA DE VIDEGARAY<\/p>\n<p>  <!--more-->  <\/p>\n<p>El candidato del PRI a la Presidencia de la Rep\u00fablica Jos\u00e9 Antonio Meade, de hace unos d\u00edas a la fecha dio el cambiazo y dej\u00f3 en el cuarto de los trebejos la llamada \u201ccandidatura ciudadana\u201d, para convertirse por urgencia y necesidad y por l\u00f3gica pol\u00edtica o sentido com\u00fan, en candidato cien por ciento priista, con chalequito rojo en busca del voto duro del partido tricolor, para ver qu\u00e9 es lo que puede alcanzar en una hora de verdadera emergencia.<br \/>Desde hace unos d\u00edas se enfund\u00f3 en el chalequito rojo del partido que lo lleva como SU candidato y mand\u00f3 al diablo \u00a0la \u201cidiota\u201d que los grandes ide\u00f3logos como VIDEGARAY, tuvieron de quitarle la candidatura a un priista, priista, como Miguel \u00c1ngel Osorio, para d\u00e1rsela a un candidato ciudadano, con la idea de no tener que pagar en la campa\u00f1a y en la votaci\u00f3n los pecados del PRI, que como gobierno sienten que tienen, sin tomar en cuenta que no s\u00f3lo perd\u00edan el apoyo ciudadano que al parecer no tienen, sino el voto de los mismos priistas que nunca vieron en Meade a un miembro de su partido, sino a un arribista, que llegaba a robar un derecho que les pertenec\u00eda a ellos en la persona de Osorio.<br \/>P\u00e9sima idea de Videgaray y de los del Itam, que pensaron en sus maromas mentales que alejando al candidato del PRI, pero exigi\u00e9ndole a los priistas su apoyo iban a ganar.<br \/>Tarde se dieron cuenta que su gran idea fue un fracaso, que no se puede hacer guisado de conejo sin conejo.<br \/>Y s\u00f3lo faltan 34 d\u00edas de campa\u00f1a.<br \/>No parece que les d\u00e9 tiempo para ganar, si acaso para pelear un buen lugar.<br \/>Se habla incluso de desavenencias serias entre Meade, Videgaray y el equipo de sabios del Itam.<br \/>Bien dicen que con Osorio otro hubiera sido el cantar, porque el PRI hubiera reaccionado distinto, porque el abanderado era de casa, de los colores del partido, de los que conocen como se hace un taco en el mercado y como se enfrenta un problema de las colonias y las broncas reales del pa\u00eds, porque ha caminado las veredas de los pueblos y las grandes avenidas de las grandes ciudades.<br \/>PINEDA GODOS<br \/>En ese sentido LEONCIO PINEDA GODOS resulta mejor estratega que VIDEGARAY, porque lleva a los candidatos del PRI de Hidalgo a la lucha electoral con la fuerza del partido en Hidalgo, con la estructura del instituto, desde sus bases, con sus sectores y organizaciones con sus comit\u00e9s municipales, y priistas comprometidos en cargos de elecci\u00f3n popular as\u00ed como los que tienen encargos y que pueden apoyar en tiempos permitidos.<br \/>Es lo que se conoce como la \u201cmaquinaria del PRI\u201d, que echada a caminar es un todo en que se involucran en una fuerza tal, que generalmente provoca victorias para el partido tricolor, porque en gran parte nace aunque les cuesta entenderlo a sus contrincantes, del orgullo de miles de sus seguidores, que encuentran en su partido respuestas a su problemas, pese a los golpes que muchas veces se llevan por malos tricolores que los hay en gran n\u00famero.<br \/>Al parecer Godos ha logrado despertar ese orgullo priista para la gran batalla para dentro de 34 d\u00edas y no ser\u00e1 cosa f\u00e1cil vencer a los priistas, pese a la ola de L\u00f3pez Obrador, sobre todo porque muchos de los candidatos del Peje tienen sobre sus espaldas la sombra de Sosa Castel\u00e1n, que no es buena, por toda la deuda que su patr\u00f3n tiene con la sociedad de Hidalgo, y de la que dio cuenta recientemente la revista PROCESO, aunque sus candidatos particularmente Lidia Garc\u00eda quiso negar in\u00fatilmente.<br \/>Por lo que se ve, en Hidalgo hay mejor estrategia para la batalla que a nivel nacional, donde Videgaray se equivoc\u00f3 hasta el grado de que cuarto para las doce mandaron al cesto de la basura su estrategia, y cambiaron a la que Godos implant\u00f3 desde el principio en esta entidad.<br \/>Cuesti\u00f3n de sentido com\u00fan y de l\u00f3gica pol\u00edtica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA ESTRATEGIA DE GODOSMEJOR QUE LA DE VIDEGARAY<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-64177","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/64177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=64177"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/64177\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=64177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=64177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=64177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}