{"id":62684,"date":"2018-05-03T13:52:09","date_gmt":"2018-05-03T13:52:09","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2018\/05\/03\/los-luchadores-que-han-muerto-en-los-ultimos-anos\/"},"modified":"2018-05-03T13:52:09","modified_gmt":"2018-05-03T13:52:09","slug":"los-luchadores-que-han-muerto-en-los-ultimos-anos","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/los-luchadores-que-han-muerto-en-los-ultimos-anos\/","title":{"rendered":"Los luchadores que han muerto en los \u00faltimos a\u00f1os"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0El Consejo Mundial de Lucha Libre confirm\u00f3 la muerte del hist\u00f3rico luchador, integrante de los Hermanos Dinamita junto a Cien Caras y M\u00e1scara A\u00f1o 2000.\u2028\u2028\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>La Lucha Libre es uno de los deportes m\u00e1s populares en nuestro pa\u00eds, llenando de luto el mundo del deporte cada que un luchador falleci\u00f3.\u2028En los \u00faltimos a\u00f1os muchos luchadores han fallecido; sin embargo aqu\u00ed dejamos una lista de los m\u00e1s recordados en los \u00faltimos a\u00f1os en nuestro pa\u00eds.\u2028Hijo del Perro Aguayo (2015)\u2028Como olvidar la tr\u00e1gica muerte de Pedro Aguayo Ram\u00edrez, mejor conocido como &#8220;El Hijo del Perro Aguayo&#8221;.\u00a0\u2028El 21 de marzo de 2015, Aguayo luch\u00f3 en Tijuana, Baja California. Durante la lucha, Rey Mysterio us\u00f3 un headscissors takedown para sacar a Aguayo del ring, pero al momento de salir no iba con el impulso necesario, Aguayo subi\u00f3 para atacar a Mysterio pero recibi\u00f3 un dropkick en la espalda media para tambi\u00e9n caer a la cuerda intermedia, cuando Mysterio aplic\u00f3 su 619, solamente Manik sali\u00f3 volando de las cuerdas, y Aguayo qued\u00f3 inconsciente. Aguayo fue llevado al hospital Del Prado, donde fue declarado muerto a la 1:00 a. m. el 21 de marzo.\u2028Fishman (2017)\u2028Tambi\u00e9n conocido como &#8220;Veneno Verde&#8221; falleci\u00f3 a los 66 a\u00f1os de edad.\u2028Cabe recordar que Fishman ten\u00eda tiempo delicado de salud, y aun as\u00ed segu\u00eda activo atendiendo a sus seguidores en firmas de aut\u00f3grafos y convenciones de lucha libre, el 8 de abril muri\u00f3 despu\u00e9s de m\u00e1s de 40 a\u00f1os dedicados a la Lucha Libre.\u2028Cosmos (2017)\u2028Luis Antonio Ju\u00e1rez Morales, de 38 a\u00f1os de edad, muri\u00f3 en su cumplimiento como Polic\u00eda al tratar de frustrar un asalto en el transporte p\u00fablico en julio de 2017.\u2028Conocido en la Lucha Libre como &#8220;Cosmos&#8221;, el luchador se sum\u00f3 a la lista de famosos atletas en pancracio que murieron.\u2028Black Silver Jr. (2018)\u2028El luchador muri\u00f3 en un accidente automovil\u00edstico en la carretera federal Acapulco-Zihuatanejo en febrero del presente a\u00f1o.\u2028Black Silver Jr., oriundo de Acapulco, Guerrero, era hijo de Black Silver, hermano de Black Silver 2000, El Hijo de Black Silver, y El Hijo de Black Silver II.\u00a0\u2028Universo 2000 (2018)\u2028El luchador Andr\u00e9s Reyes Gonz\u00e1lez, mejor conocido como Universo 2000, falleci\u00f3 1l 1 de mayo a los 55 a\u00f1os de edad.\u2028El Consejo Mundial de Lucha Libre confirm\u00f3 la muerte del hist\u00f3rico luchador, integrante de los Hermanos Dinamita junto a Cien Caras y M\u00e1scara A\u00f1o 2000.\u2028\u2028<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0El Consejo Mundial de Lucha Libre confirm\u00f3 la muerte del hist\u00f3rico luchador, integrante de los Hermanos Dinamita junto a Cien Caras y M\u00e1scara A\u00f1o 2000.\u2028\u2028\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-62684","post","type-post","status-publish","format-standard","hentry","category-deportiva"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/62684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=62684"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/62684\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=62684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=62684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=62684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}