{"id":56881,"date":"2018-02-08T15:24:19","date_gmt":"2018-02-08T15:24:19","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2018\/02\/08\/laguna-de-voces-337\/"},"modified":"2018-02-08T15:24:19","modified_gmt":"2018-02-08T15:24:19","slug":"laguna-de-voces-337","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/laguna-de-voces-337\/","title":{"rendered":"LAGUNA DE VOCES"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0Hace 13 a\u00f1os\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Por supuesto que nunca ser\u00e1 lo mismo poner en marcha una rotativa, que prender la computadora, enlazarse al internet y luego al escritorio virtual donde se administra un portal informativo. No hay comparaci\u00f3n en el trance po\u00e9tico incluso que representa ver el momento en que llega la pesad\u00edsima m\u00e1quina en un tr\u00e1iler, ser testigo del momento crucial en que es bajada de la plataforma con un montacargas, y la colocaci\u00f3n exacta, casi milim\u00e9trica, sobre el piso doblemente reforzado y rodeado de poliuretano para evitar resquebrajaduras al momento en que suena la chicharra y empiezan a dar vueltas los rodillos.<br \/>\u00a0\u00a0 \u00a0Pasar semanas completas sin dormir a la espera de encontrar el ritmo adecuado que permitiera tener todas las p\u00e1ginas del diario listas en l\u00e1minas, luego del proceso casi artesanal de esos tiempos en que se filmaba una vez que dise\u00f1o daba luz verde; posteriormente la insoladora, el revelado de la placa, hasta que llegaba a los prensistas para fuera colocada en el lugar correspondiente.<br \/>\u00a0\u00a0 \u00a0Noches, madrugadas sin dormir, con apenas una secci\u00f3n a las cinco de la ma\u00f1ana, y la rotativa que simplemente no arrancaba porque los pasos anteriores se trababan, entre la desesperaci\u00f3n, la novatez, y de plano el enojo del ingeniero Jos\u00e9 Luis Boschetti, quien instal\u00f3 la Goss Urbanite, al manifestar que as\u00ed de plano nunca \u00edbamos a salir.<br \/>\u00a0\u00a0 \u00a0Hasta que la noche del 7 de febrero de hace 13 a\u00f1os decidimos que al otro d\u00eda estar\u00edamos en las calles pasara lo que pasara. Y sucedi\u00f3 el milagro, porque la edici\u00f3n estaba lista para ser repartida mucho antes de las horas en que nos d\u00e1bamos por vencidos, y aplaz\u00e1bamos una vez m\u00e1s el momento para salir a la luz p\u00fablica.<br \/>\u00a0\u00a0 \u00a0Desde entonces a este nuevo 8 de febrero del 2018, hemos cumplido el ritual cotidiano que implica editar un peri\u00f3dico diario, sin faltar una sola vez a nuestro compromiso de llevarle a usted \u201cla historia de cada d\u00eda\u201d, de acompa\u00f1arle en la posibilidad de entender la realidad del Estado, el pa\u00eds y el mundo. <br \/>\u00a0\u00a0 \u00a0Hace justo ese tiempo, quien escribe esta columna desempe\u00f1aba el cargo de Director General, que pasados cuatro a\u00f1os asumi\u00f3 mi hermano Adalberto, despu\u00e9s Mart\u00edn, y luego reiniciar este viaje siempre fascinante de dar vida a un medio informativo netamente hidalguense, orgulloso de tener su casa matriz editora aqu\u00ed, en Pachuca.<br \/>\u00a0\u00a0 \u00a0Puede uno pecar de rom\u00e1ntico, pero estoy cierto que los impresos nunca desaparecer\u00e1n con todo y la abrumadora presencia de medios digitales. Hoy mismo, luego de la explosi\u00f3n de nuevos portales, empieza a darse una depuraci\u00f3n que resultaba l\u00f3gica, en donde la mejor garant\u00eda de credibilidad es que exista un soporte llamado peri\u00f3dico salido de la rotativa.<br \/>\u00a0\u00a0 \u00a0Lo anterior de ninguna manera quiere decir que Diario Plaza Ju\u00e1rez no haya invertido recursos, tiempo y esfuerzos en su portal informativo. Por el contrario, en la medida de las posibilidades se trabaja en esa \u00e1rea, que tendr\u00e1 un impulso definitivo en este 2018, para dar vida al medio digital m\u00e1s importante en el Estado de Hidalgo y la regi\u00f3n.<br \/>\u00a0\u00a0 \u00a0Somos los primeros en contar con una estaci\u00f3n de radio a trav\u00e9s de internet, con programaci\u00f3n diaria en nuestros estudios. Es pues que s\u00ed, somos profundamente rom\u00e1nticos en el proceso siempre \u00fanico de ver como una s\u00e1bana de papel salida de una bobina se impregna con letras, fotograf\u00edas y colores. Sin duda alguna este prodigio de todas las madrugadas en el taller enamora, siempre despierta el gusto por toda la magia que implica.<br \/>\u00a0\u00a0 \u00a0Pero tambi\u00e9n vemos, disfrutamos de la absoluta inmediatez que representan las nuevas herramientas del internet, tambi\u00e9n sus riesgos cuando la premura deja de lado la reflexi\u00f3n y el sentido com\u00fan.<br \/>\u00a0\u00a0 \u00a0Compartimos con usted estos primeros 13 a\u00f1os de vida. Nos enorgullece ser un medio informativo que naci\u00f3 aqu\u00ed, en tierras hidalguenses, que apost\u00f3 todo su capital de vida al periodismo en la tierra que vio nacer a nuestros hijos, que seguramente nos ver\u00e1 partir siempre aqu\u00ed, donde el destino y el amor nos trajo.<br \/>Mil gracias, hasta ma\u00f1ana.<br \/>jeperalta@plazajuarez.mx\/historico\/historico<br \/>@JavierEPeralta<\/p>\n<p>CITA:<br \/>\u00a0\u00a0 \u00a0Puede uno pecar de rom\u00e1ntico, pero estoy cierto que los impresos nunca desaparecer\u00e1n con todo y la abrumadora presencia de medios digitales. Hoy mismo, luego de la explosi\u00f3n de nuevos portales, empieza a darse una depuraci\u00f3n que resultaba l\u00f3gica, en donde la mejor garant\u00eda de credibilidad es que exista un soporte llamado peri\u00f3dico salido de la rotativa.\u00a0\u00a0 \u00a0<br \/>\u00a0\u00a0 \u00a0<br \/>\u00a0\u00a0 \u00a0<br \/>\u00a0\u00a0 \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0Hace 13 a\u00f1os\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-56881","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/56881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=56881"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/56881\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=56881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=56881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=56881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}