{"id":55372,"date":"2018-01-12T15:11:37","date_gmt":"2018-01-12T15:11:37","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2018\/01\/12\/michael-j-fox-regresa-a-la-television\/"},"modified":"2018-01-12T15:11:37","modified_gmt":"2018-01-12T15:11:37","slug":"michael-j-fox-regresa-a-la-television","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/michael-j-fox-regresa-a-la-television\/","title":{"rendered":"Michael J. Fox regresa a la televisi\u00f3n"},"content":{"rendered":"<p>El actor tendr\u00e1 un papel dentro de la serie de ABC Designated Survivor<\/p>\n<p>  <!--more-->  <\/p>\n<p>Despu\u00e9s de unos a\u00f1os fuera del medio, este 2018 Michael J. Fox regresar\u00e1 a la televisi\u00f3n y lo har\u00e1 al lado de Kiefer Sutherland. Y es que el veterano int\u00e9rprete tendr\u00e1 un papel recurrente en la serie de televisi\u00f3n estadounidense Designated Survivor que transmite la cadena ABC y que difunde Netflix fuera de Estados Unidos. <br \/>El a\u00f1o pasado el actor tuvo una corta participaci\u00f3n en un episodio de la nueva temporada de Curb Your Enthusiasm, pero para la nueva temporada del drama de ABC ser\u00e1 parte de un arco argumental de cinco episodios en el que interpretar\u00e1 a un abogado encargado de investigar al ex presidente por supuestas filtraciones de informaci\u00f3n confidencial.<br \/>Por el momento el show no est\u00e1 emitiendo nuevos episodios pero continuar\u00e1 con el resto de su temporada actual el pr\u00f3ximo 28 de febrero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor tendr\u00e1 un papel dentro de la serie de ABC Designated Survivor<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-55372","post","type-post","status-publish","format-standard","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/55372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=55372"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/55372\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=55372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=55372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=55372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}