{"id":51765,"date":"2017-11-09T12:17:40","date_gmt":"2017-11-09T12:17:40","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/11\/09\/comienza-retiro-de-esculturas-de-tolsa-en-catedral-de-la-cdmx\/"},"modified":"2017-11-09T12:17:40","modified_gmt":"2017-11-09T12:17:40","slug":"comienza-retiro-de-esculturas-de-tolsa-en-catedral-de-la-cdmx","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/comienza-retiro-de-esculturas-de-tolsa-en-catedral-de-la-cdmx\/","title":{"rendered":"Comienza retiro de esculturas de Tols\u00e1 en Catedral de la CDMX"},"content":{"rendered":"<p>Las esculturas de la Catedral Metropolitana que resistieron el sismo del 19 de septiembre ser\u00e1n retiradas este mi\u00e9rcoles de la fachada del inmueble, en lo que ser\u00e1 una proeza de la ingenier\u00eda por la complejidad de la maniobra, que inici\u00f3 desde las 8 de la ma\u00f1ana y se prolongar\u00e1 todo el d\u00eda.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La &#8220;Fe&#8221;, la &#8220;Caridad&#8221; y la &#8220;Esperanza&#8221;, obras de Manuel Tols\u00e1, pesan alrededor de 3.5 toneladas cada una. Para bajar las primeras (ya que la &#8220;Esperanza&#8221; cay\u00f3 por el temblor, fragment\u00e1ndose en dos partes) se emplear\u00e1 una gr\u00faa hidr\u00e1ulica con capacidad de 220 toneladas.<br \/>La gr\u00faa no puede entrar al atrio para no da\u00f1ar los vestigios prehisp\u00e1nicos que hay abajo, por lo que cuenta con un brazo &#8220;extendido e inclinado para alcanzar los 45 metros de altura y una distancia de 35 metros de la fachada&#8221;, explic\u00f3 Ra\u00fal Delgado, director de Sitios y Monumentos del Patrimonio Cultural de la Secretar\u00eda de Cultura federal.<br \/>El funcionario explic\u00f3 que en el procedimiento se emplear\u00e1n eslingas, &#8220;una especie de red con un material muy resistente de poli\u00e9ster y fibra de carbono&#8221; con las que se envolver\u00e1n las esculturas. Estos materiales tienen textura suave para no lastimar las piezas y &#8220;es la manera m\u00e1s segura de bajarlas&#8221;, pues de manera previa empresas especializadas en seguridad estructural estudiaron el plan.<br \/>Asimismo, detall\u00f3 Delgado, al ser una operaci\u00f3n riesgosa se previeron varias medidas de seguridad, como un buen margen en la capacidad de las gr\u00faas, seguro contra da\u00f1os a terceros y seguro para las piezas.<br \/>\u00a0<br \/>Tambi\u00e9n record\u00f3 que, una vez abajo, la &#8220;Fe&#8221;, la &#8220;Esperanza&#8221; y la &#8220;Caridad&#8221; ser\u00e1n enviadas a restauraci\u00f3n pues &#8220;desde 1813 que fueron colocadas han estado expuestas al viento, a los cambios de temperatura, a las vibraciones y al ambiente \u00e1cido&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las esculturas de la Catedral Metropolitana que resistieron el sismo del 19 de septiembre ser\u00e1n retiradas este mi\u00e9rcoles de la fachada del inmueble, en lo que ser\u00e1 una proeza de la ingenier\u00eda por la complejidad de la maniobra, que inici\u00f3 desde las 8 de la ma\u00f1ana y se prolongar\u00e1 todo el d\u00eda.<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-51765","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/51765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=51765"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/51765\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=51765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=51765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=51765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}