{"id":51626,"date":"2017-11-07T12:42:53","date_gmt":"2017-11-07T12:42:53","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/11\/07\/laguna-de-voces-296\/"},"modified":"2017-11-07T12:42:53","modified_gmt":"2017-11-07T12:42:53","slug":"laguna-de-voces-296","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/laguna-de-voces-296\/","title":{"rendered":"LAGUNA DE VOCES"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0La vida no es asunto de recetas pol\u00edticas\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Desde tiempos inmemoriales hemos visto crecer la vida en el cielo con lunas que brillan, se hacen grandes, a veces solo una franja curva, otras un sol anaranjado, pero siempre testimonio de que nada est\u00e1 quieto, que todo se mueve incesantemente. Igual en los campos con la hierba que inunda las tierras y debe ser arrancada para que no se coma la siembra. Lo mismo en la lucha eterna por el poder donde se inventan m\u00e1scaras para ser una vez \u00e1ngeles, otras demonios, otras nada, porque la nada existe en esos territorios llenos de misterio.<br \/>\u00a0\u00a0 \u00a0La constancia es que solo lo muerto se queda est\u00e1tico, listo para volar a los lugares donde ya nada crece como no sea el olvido. As\u00ed, cuando la edad se agolpa encima de los hombros, todo empieza a ser m\u00e1s lento, pr\u00f3ximo a detenerse porque el tiempo as\u00ed lo determina en una contradicci\u00f3n porque su tarea fundamental es precisamente hacer que pasen los segundos, las horas, la vida.<br \/>\u00a0\u00a0 \u00a0Gozamos del sue\u00f1o porque sabemos que es un simple descanso para volver a caminar, a respirar el aire de las madrugadas cuando a las cuatro de la ma\u00f1ana despertamos para tener constancia de que todav\u00eda seguimos aqu\u00ed, o un recuerdo se hizo tan urgente que el miedo de olvidarlo nos hizo abrir los ojos.<br \/>\u00a0\u00a0 \u00a0Los cad\u00e1veres por eso tienen un profundo gesto de sorpresa, porque est\u00e1 claro que siempre hay un intento final por no quererse dejar llevar por la que tarde o temprano lo har\u00e1, pero siempre hay una lucha hasta el final, que est\u00e1 por dem\u00e1s perdida cuando la decisi\u00f3n est\u00e1 dada.<br \/>\u00a0\u00a0 \u00a0Durante casi toda la existencia apuramos la vocaci\u00f3n de la vida, y las ansias de correr que exist\u00edan cuando ni\u00f1os se pierde poco a poco, hasta que regresamos, en ese c\u00edrculo constante que es vivir, a la edad en que deseamos poder brincar por todos lados, demostrar que somos los de hace d\u00e9cadas. Por un momento festejamos que podemos pegar un salto y dejar el bal\u00f3n en la canasta, o volar a lado izquierdo para detener el inminente gol, con todo y que el golpazo parezca el de un costal de papas.<br \/>\u00a0\u00a0 \u00a0Movernos es la constancia, porque al rev\u00e9s de la pol\u00edtica, el que no se mueve empieza a llamar la atenci\u00f3n de la muerte, que puede ser enga\u00f1ada en la segunda infancia que dura lo que la ilusi\u00f3n de que un marat\u00f3n completo est\u00e1 al alcance de la mano. Sin embargo insistimos hasta el absurdo en el gusto por enga\u00f1ar y enga\u00f1arnos.<br \/>\u00a0\u00a0 \u00a0Malo, muy malo cuando deja de funcionar un pie, o y entrados en los 70s de pronto se empiezan a quebrar los huesos que se convierten en cristaler\u00eda fina, delicada.<br \/>\u00a0\u00a0 \u00a0Pero hay que estar en movimiento, darse el gusto de que la de guada\u00f1a en mano nos vea y se crea la historia de que recuperamos el gusto por el ejercicio, el trabajo hasta bien entrada la noche, el sue\u00f1o de que la felicidad existe.<br \/>\u00a0\u00a0 \u00a0La vida no es asunto de recetas pol\u00edticas, y siempre ser\u00e1 preciso dar signos de que la vida transcurre fresca y sonriente entre nosotros. Al que se le queda la ma\u00f1a de pedir que lo den por muerto, efectivamente queda muerto.<br \/>\u00a0\u00a0 \u00a0Todo est\u00e1 en movimiento y eso anima a unirse de lleno al universo que un d\u00eda crece, otro explota para formar galaxias, pero hasta la eternidad caminar\u00e1 con un rumbo que sepa Dios a d\u00f3nde conduce.<br \/>\u00a0\u00a0 \u00a0La noche que espera siempre al que escribe a deshoras es prueba irrefutable de que hay movimiento, de que al rato saldr\u00e1 de nueva cuenta el sol y seguir\u00e1 la historia por los siglos de los siglos.<\/p>\n<p>Mil gracias, hasta ma\u00f1ana.<br \/>jeperalta@plazajuarez.mx\/historico\/historico<br \/>@JavierEPeralta\u00a0\u00a0 \u00a0<\/p>\n<p>CITA:<br \/>Durante casi toda la existencia apuramos la vocaci\u00f3n de la vida, y las ansias de correr que exist\u00edan cuando ni\u00f1os se pierde poco a poco, hasta que regresamos, en ese c\u00edrculo constante que es vivir, a la edad en que deseamos poder brincar por todos lados, demostrar que somos los de hace d\u00e9cadas. Por un momento festejamos que podemos pegar un salto y dejar el bal\u00f3n en la canasta, o volar a lado izquierdo para detener el inminente gol, con todo y que el golpazo parezca el de un costal de papas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0La vida no es asunto de recetas pol\u00edticas\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-51626","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/51626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=51626"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/51626\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=51626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=51626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=51626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}