{"id":48760,"date":"2017-10-04T04:10:57","date_gmt":"2017-10-04T04:10:57","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/10\/04\/anuncian-creditos-para-empresas-damnificadas\/"},"modified":"2017-10-04T04:10:57","modified_gmt":"2017-10-04T04:10:57","slug":"anuncian-creditos-para-empresas-damnificadas","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/anuncian-creditos-para-empresas-damnificadas\/","title":{"rendered":"Anuncian cr\u00e9ditos para empresas damnificadas"},"content":{"rendered":"<p>Apoyo a empresas afectadas por los terremotos<\/p>\n<p>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Habr\u00e1 tres tipos de cr\u00e9ditos\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Ildefonso Guajardo, secretario de Econom\u00eda anunci\u00f3 que en las entidades que registraron da\u00f1os con el terremoto del 19 se septiembre se espera concluir el inventario de empresas afectadas a finales de esta semana \u201cy estaremos listos para hacer exactamente lo que hicimos en Oaxaca\u201d. Los primeros cheques se comenzaron a dar la v\u00edspera para microempresas de Oaxaca que tuvieron afectaciones en sus inventarios<br \/>El secretario explic\u00f3 que se dise\u00f1aron \u201ctres paquetes de cr\u00e9dito\u201d. Los primeros van destinados a las empresas o negocios m\u00e1s peque\u00f1os y tienen que ver con el r\u00e9gimen de incorporaci\u00f3n fiscal (RIF). En este caso el monto de los cr\u00e9ditos que se otorgar\u00e1n van desde los 50 mil a los 300 mil pesos y para lo cual, dijo, \u201ctenemos una capacidad de hasta mil millones de pesos\u201d.<br \/>El segundo tipo de cr\u00e9dito es hasta por 2 millones de pesos y se otorgar\u00e1 en conjunto con los gobiernos de Chiapas y Oaxaca para apoyar a empresas m\u00e1s grandes e incluso para la reposici\u00f3n de instalaciones que hayan resultado da\u00f1adas severamente. En conjunto, se tienen recursos por 350 millones de pesos.<br \/>Para el tercer y \u00faltimo paquete de cr\u00e9ditos se cuenta con una disposici\u00f3n de 60 millones de pesos. Son pr\u00e9stamos m\u00e1s flexibles que las empresas podr\u00e1n contratar desde 300 mil y hasta 500 mil pesos, con posibilidades de que la tasa de inter\u00e9s baje hasta cuatro puntos si hay pronto pago o ahorro de los solicitantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apoyo a empresas afectadas por los terremotos \u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Habr\u00e1 tres tipos de cr\u00e9ditos\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-48760","post","type-post","status-publish","format-standard","hentry","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/48760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=48760"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/48760\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=48760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=48760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=48760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}