{"id":48282,"date":"2017-09-25T04:16:52","date_gmt":"2017-09-25T04:16:52","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/09\/25\/inmuebles-operados-por-ocesa-se-hallan-en-buenas-condiciones\/"},"modified":"2017-09-25T04:16:52","modified_gmt":"2017-09-25T04:16:52","slug":"inmuebles-operados-por-ocesa-se-hallan-en-buenas-condiciones","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/inmuebles-operados-por-ocesa-se-hallan-en-buenas-condiciones\/","title":{"rendered":"Inmuebles operados por Ocesa se hallan en buenas condiciones"},"content":{"rendered":"<p>Ocesa explic\u00f3 tambi\u00e9n que los inmuebles fueron examinados por un Director Responsable de Obra y un Corresponsal T\u00e9cnico de Estructuras, de acuerdo con el Reglamento de Construcciones vigente<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los recintos administrados u operados por Ocesa fueron examinados para validar su situaci\u00f3n y se concluy\u00f3 que se encuentran en buenas condiciones. <br \/>A trav\u00e9s de un comunicado publicado en su cuenta de Twitter, la empresa se\u00f1al\u00f3 que se hizo la revisi\u00f3n del Foro Sol, Aut\u00f3dromo Hermanos Rodr\u00edguez, Estadio Azul, Palacio de los Deportes, Pabell\u00f3n Cuervo, Teatro Metrop\u00f3litan, Teatro Telcel y Teatro Insurgentes y sus instalaciones pueden usarse con normalidad.<br \/>Adem\u00e1s, se indic\u00f3 que en el caso del Plaza Condesa tampoco hay da\u00f1o estructural y est\u00e1 en &#8220;\u00f3ptimas condiciones&#8221;. Sin embargo, est\u00e1 &#8220;en una zona muy golpeada por el sismo y tomaremos eso en cuenta&#8221; antes de retomar actividades.<br \/>Ocesa explic\u00f3 tambi\u00e9n que los inmuebles fueron examinados por un Director Responsable de Obra y un Corresponsal T\u00e9cnico de Estructuras, de acuerdo con el Reglamento de Construcciones vigente. <br \/>Tambi\u00e9n, dijo, los eventos programados para el pasado fin de semana ser\u00e1n reprogramados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocesa explic\u00f3 tambi\u00e9n que los inmuebles fueron examinados por un Director Responsable de Obra y un Corresponsal T\u00e9cnico de Estructuras, de acuerdo con el Reglamento de Construcciones vigente<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-48282","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/48282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=48282"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/48282\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=48282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=48282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=48282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}