{"id":48281,"date":"2017-09-25T04:15:59","date_gmt":"2017-09-25T04:15:59","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/09\/25\/usan-escaner-en-el-cine-opera-para-determinar-su-estado\/"},"modified":"2017-09-25T04:15:59","modified_gmt":"2017-09-25T04:15:59","slug":"usan-escaner-en-el-cine-opera-para-determinar-su-estado","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/usan-escaner-en-el-cine-opera-para-determinar-su-estado\/","title":{"rendered":"Usan esc\u00e1ner en el cine \u00d3pera para determinar su estado"},"content":{"rendered":"<p>El pr\u00f3ximo mi\u00e9rcoles tendr\u00e1n el dictamen de todo el edificio que data de 1942<\/p>\n<p>  <!--more-->  <\/p>\n<p>El Cine \u00d3pera es uno de los 56 inmuebles que el Instituto Nacional de Bellas Artes escanear\u00e1 con tecnolog\u00eda de punta tras sufrir da\u00f1os por el sismo de 7.1 grados, que impact\u00f3 la Ciudad de M\u00e9xico, el pasado 19 de septiembre. Se suma a otras edificaciones ya analizadas por la empresa como la Torre de Investigaciones del Cenart y el Museo Diego Rivera.<br \/>La empresa de arquitectura Ciberna S.A de C.V., que desde hace 40 a\u00f1os se dedica al mantenimiento de inmuebles, fue contratada por el INBA y desde el pasado jueves hace el escaneo, con un equipo \u00fanico en Am\u00e9rica Latina, de 56 inmuebles art\u00edsticos de la Ciudad de M\u00e9xico. Esta semana har\u00e1n el an\u00e1lisis estructural del Palacio de Bellas Artes, el Conservatorio Nacional de M\u00fasica, el Antiguo Colegio de San Ildefonso y el Museo Nacional de San Carlos.<br \/>Este domingo, luego de que un grupo de vecinos de la colonia San Rafael cerrara la calle Serapio Rend\u00f3n para exigir una revisi\u00f3n exhaustiva al Cine \u00d3pera \u2014incluso algunos piden su demolici\u00f3n\u2014 el responsable de Protecci\u00f3n Civil del INBA, se present\u00f3 con t\u00e9cnicos de Ciberna S.A de C.V, liderados por el ingeniero Manuel Alatriste, para se\u00f1alar que el edificio que data de 1942 est\u00e1 siendo escaneado con un sistema automatizado vectorial l\u00e1ser para conocer su estado.<br \/>En entrevista, Alatriste dijo que este equipo que hace mediciones de 360 grados, trabaja con rayo l\u00e1ser y manda un mill\u00f3n de puntos por segundo a una supercomputadora y \u00e9sta los convierte en im\u00e1genes. &#8220;Esto nos da como resultado un diagn\u00f3stico que nos indica si hay fracturas o no hay fracturas, si hay deformaciones, inclinaciones o si el edificio sufri\u00f3 movimientos. Es una tecnolog\u00eda que se est\u00e1 utilizando en Europa y Estados Unidos, es una tecnolog\u00eda norteamericana, y este equipo es el primero que existe en Am\u00e9rica Latina y lo tenemos aqu\u00ed en M\u00e9xico. Se manda una copia a Estados Unidos que nos avala el dictamen junto con el que hace M\u00e9xico&#8221;, dijo Manuel Alatriste.<br \/>Aun antes de tener los resultados \u2014ser\u00e1 el mi\u00e9rcoles\u2014, el INBA autoriz\u00f3 la demolici\u00f3n de la saliente derecha del Cine \u00d3pera por el riesgo que implica. El pr\u00f3ximo mi\u00e9rcoles tendr\u00e1n el dictamen de todo el edificio. Ayer, antes de las dos de la tarde, t\u00e9cnicos de la empresa, del INBA y de Protecci\u00f3n Civil de la delegaci\u00f3n Cuauht\u00e9moc, a cargo de Cintia Murrieta, entraron al edificio sin permitir el acceso de vecinos que han manifestado su descontento pero que aceptaron esperar al mi\u00e9rcoles para conocer el diagn\u00f3stico.<br \/>Manuel Alatriste reiter\u00f3 que escanear\u00e1n 56 inmuebles. &#8220;A\u00fan no tenemos los resultados, se van a ir dando d\u00eda con d\u00eda&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo mi\u00e9rcoles tendr\u00e1n el dictamen de todo el edificio que data de 1942<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-48281","post","type-post","status-publish","format-standard","hentry","category-arteria-cultural"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/48281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=48281"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/48281\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=48281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=48281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=48281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}