{"id":47417,"date":"2017-09-07T15:57:13","date_gmt":"2017-09-07T15:57:13","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/09\/07\/orden-en-los-centros-de-verificacion-vehicular\/"},"modified":"2017-09-07T15:57:13","modified_gmt":"2017-09-07T15:57:13","slug":"orden-en-los-centros-de-verificacion-vehicular","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/orden-en-los-centros-de-verificacion-vehicular\/","title":{"rendered":"\u201cOrden en los centros de verificaci\u00f3n vehicular\u201d"},"content":{"rendered":"<p>INDICADORES ALCANZADOS POR SEMARNATH <\/p>\n<p>  <!--more-->  <\/p>\n<p>Benjam\u00edn Rico Moreno, titular de la Secretar\u00eda de Medio Ambiente y Recursos Naturales de Hidalgo (SEMARNATH), inform\u00f3 respecto\u00a0 a los temas alcanzados a un a\u00f1o de estar al frente de la dependencia.<br \/>Detall\u00f3 que de 63 centros que operaban en la entidad, actualmente solo 50 brindan sus servicios, pues fueron cesados por incumplimiento de las reglas y lineamientos; o para atender las observaciones otros siguen un procedimiento administrativo para obtener su autorizaci\u00f3n. <br \/>Tambi\u00e9n se alcanz\u00f3 la digitalizaci\u00f3n del tr\u00e1mite de evaluaci\u00f3n de impacto ambiental, lo que permite procesos transparentes y \u00e1giles, pago en l\u00ednea y disminuci\u00f3n de costos a los usuarios.<br \/>Enfatiz\u00f3 en la coordinaci\u00f3n estrecha entre las instancias del gobierno para garantizar proyectos e inversiones sustentables; bajo la encomienda de pleno respeto al medio ambiente.<br \/>En otros puntos logrados, el funcionario estatal se\u00f1al\u00f3 que junto con la Comisi\u00f3n Nacional de \u00c1reas Naturales Protegidas (CONANP) se implement\u00f3 el Programa Integral de Conservaci\u00f3n del Puma detectado en Actopan.<br \/>As\u00ed como el fortalecimiento del sistema de monitoreo de Calidad del Aire con una inversi\u00f3n de m\u00e1s de 15 millones de pesos para obtener informaci\u00f3n de las condiciones del aire que respiran las familias en 13 municipios del Estado.<br \/>Se suman a estos alcances la implementaci\u00f3n de PROAIRE y el Inventario de Emisiones del Estado de Hidalgo.<br \/>Adem\u00e1s de los convenios de colaboraci\u00f3n con la CONANP para fortalecer las 54 \u00e1reas naturales protegidas que existen en Hidalgo, con una inversi\u00f3n de 14.8 millones de pesos en programas de manejo sostenible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INDICADORES ALCANZADOS POR SEMARNATH<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-47417","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/47417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=47417"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/47417\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=47417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=47417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=47417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}