{"id":45912,"date":"2017-08-09T11:33:32","date_gmt":"2017-08-09T11:33:32","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/08\/09\/deportes-nacional-e-internacional-10\/"},"modified":"2017-08-09T11:33:32","modified_gmt":"2017-08-09T11:33:32","slug":"deportes-nacional-e-internacional-10","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/deportes-nacional-e-internacional-10\/","title":{"rendered":"Deportes Nacional e Internacional"},"content":{"rendered":"<p>#NBA <br \/>Westbrook estar\u00e1 en M\u00e9xico con el Thunder<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0Westbrook fue nombrado recientemente como MVP de la NBA, tras ganar el premio a James Harden de los Houston Rockets y Kawhi Leonard de los Spurs.\u2028\u2028\u2028<br \/>Los pr\u00f3ximos 7 y 9 de diciembre la Ciudad de M\u00e9xico volver\u00e1 a tener dos partidos oficiales de la NBA, cuando los Nets de Brooklyn act\u00faen como locales administrativos contra el Thunder de Oklahoma y Heat de Miami.\u2028El actual MVP de la Liga, Russell Westbrook visitar\u00e1 nuestro pa\u00eds al mando del Thunder.\u2028Westbrook fue nombrado recientemente como MVP de la NBA, tras ganar el premio a James Harden de los Houston Rockets y Kawhi Leonard de los Spurs.\u2028Hoy se realizar\u00e1 el anuncio oficial en un Facebook Live que realizar\u00e1 la oficina de la NBA en M\u00e9xico.\u2028A\u00fan no se revelan los detalles de la venta de boletos, pero se espera que se realice con el sistema de pre-registro, similar al que implement\u00f3 la NFL.\u2028La NBA comenz\u00f3 su aventura en nuestro pa\u00eds en 1992. Ser\u00e1n los partidos 25 y 26 que se realicen en M\u00e9xico, la mayor cantidad fuera de Estados Unidos y Canad\u00e1.<br \/>**<br \/>#BOX<br \/>\u00a0<br \/>R\u00e9cord de Gennady Golovkin motiva al &#8220;Canelo&#8221;<\/p>\n<p>Gennady Golovkin nunca ha perdido una pelea (37-0-0, 33KO). El kazajo tampoco ha sido derribado en su carrera profesional. Es favorito en las apuestas. A Sa\u00fal &#8220;Canelo&#8221; \u00c1lvarez estos ingredientes le apetece para vencer a su rival el 16 de septiembre y protagonizar una de las grandes victorias del boxeo mexicano.\u2028A mes y medio de la pelea, Canelo (49-1-1,34KO) se\u00f1ala que se encuentra en un momento cumbre de su carrera y con el potencial no s\u00f3lo para destronar a Golovkin, sino de paso noquearlo.\u2028&#8221;He aprendido mucho desde la derrota con Floyd (Mayweather). Tengo m\u00e1s confianza, soy m\u00e1s maduro, con m\u00e1s experiencia. Estoy en un punto importante de mi carrera gracias a las peleas que he tenido. Creo que s\u00ed puedo noquear a Golovkin&#8221;, declar\u00f3 \u00c1lvarez.\u2028Canelo entiende que los triunfos por la v\u00eda del cloroformo crean \u00eddolos. Las grandes victorias con el poder de los pu\u00f1os encumbraron a Julio C\u00e9sar Ch\u00e1vez, Salvador S\u00e1nchez, Juan Manuel M\u00e1rquez, entre otros grandes nombres a los que el tapat\u00edo quiere emular.\u2028&#8221;Hay varias grandes peleas que fueron hechas por mexicanos. Pienso que esta pelea pudiera marcar un antes y despu\u00e9s&#8221;, reflexion\u00f3.\u2028El campe\u00f3n en dos categor\u00edas diferentes coment\u00f3 que s\u00ed recuerda cuando realiz\u00f3 una sesi\u00f3n como sparring con Golovkin, pero advirti\u00f3 que no puede tomar ese entrenamiento como base.\u2028&#8221;El Canelo&#8221; mantendr\u00e1 sus entrenamientos en San Diego hasta el 10 de septiembre, cuando tomar\u00e1 el vuelo a Las Vegas para la gran funci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#NBA Westbrook estar\u00e1 en M\u00e9xico con el Thunder<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-45912","post","type-post","status-publish","format-standard","hentry","category-deportiva"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/45912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=45912"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/45912\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=45912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=45912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=45912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}