{"id":44823,"date":"2017-07-19T13:38:48","date_gmt":"2017-07-19T13:38:48","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/07\/19\/retratos-hablados-414\/"},"modified":"2017-07-19T13:38:48","modified_gmt":"2017-07-19T13:38:48","slug":"retratos-hablados-414","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/retratos-hablados-414\/","title":{"rendered":"RETRATOS HABLADOS"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0M\u00e1s dinero a los fraccionadores\u2028<br \/>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0MINUTARIO\u2028<\/p>\n<p>  <!--more-->  <\/p>\n<p>Algo grave y complicado pasa, cuando la presidencia municipal de Pachuca decide no dar a conocer la identidad de las constructoras que recibieron el benepl\u00e1cito del ayuntamiento para la construcci\u00f3n de nuevos fraccionamientos en la capital hidalguense. Algo dif\u00edcil de entender, fundamentalmente porque el negocio de construir casas al por mayor que solo complican, a\u00fan m\u00e1s, el desarrollo de una capital, tiene como beneficiarios a unos cuantos y afecta a muchos.<br \/>\u00a0\u00a0 \u00a0Sin embargo, y pese al \u201cprofundo respeto\u201d que se manifest\u00f3 hacia los empresarios de la construcci\u00f3n, que no a la ciudadan\u00eda, es evidente que no resulta complicado identificar a quienes desde hace mucho tiempo se han visto beneficiados con el otorgamiento de permisos para edificar viviendas, que ya no son necesarias.<br \/>\u00a0\u00a0 \u00a0Hay una sobre oferta y eso todos lo saben. Vaya pues, no se descubre ning\u00fan misterio cuando se pone en la mesa una necesidad imperiosa, que es terminar con los monopolios inmobiliarios que hacen mucho dinero con poco esfuerzo.<br \/>\u00a0\u00a0 \u00a0El meollo del asunto es conseguir que la autoridad autorice el uso del suelo, y de este modo el que hace casas sabe de antemano que lograr\u00e1 ganancias arriba del 500 por ciento, si no es que m\u00e1s, porque sabe, bien que lo sabe, que no hay mejor negocio que ese precisamente.<br \/>\u00a0\u00a0 \u00a0A lo anterior se suma una actitud plena de confrontaci\u00f3n con el gobierno estatal, que plante\u00f3 como parte esencial de su proyecto de desarrollo urbano, impedir el otorgamiento de nuevos permisos para la edificaci\u00f3n de vivienda en Pachuca y Mineral de la Reforma, porque solo se traducen en problemas.<br \/>\u00a0\u00a0 \u00a0Problemas porque no son pocos los casos en que se inauguran pomposamente fraccionamientos que al final resulta que no tienen servicios primarios, pero adem\u00e1s no son habitados, porque la idea de que es toda una inversi\u00f3n aplicar el cr\u00e9dito de INFONAVIT en una casita siempre resulta todo lo contrario.<br \/>\u00a0\u00a0 \u00a0El espejismo anotado ha cobrado cientos de v\u00edctimas, que ni se trasladan a vivir a Pachuca, pero tampoco pueden participar en el mejoramiento de la colonia, lo que da como resultado que lugares deshabitados se conviertan en refugio para delincuentes o la invasi\u00f3n a cargo de supuestas organizaciones que defienden los derechos de los pobres en el mejor de los casos.<br \/>\u00a0\u00a0 \u00a0Por todo lo anterior no se entiende la actitud de la alcald\u00eda pachuque\u00f1a, que por razones tal vez explicables pero no explicadas, opt\u00f3 por ceder ante cada vez m\u00e1s voraces fraccionadores que evidentemente nunca se dar\u00e1n por satisfechos.<br \/>\u00a0\u00a0 \u00a0De este modo resultaba de inter\u00e9s p\u00fablico se informara qui\u00e9n o qui\u00e9nes se benefician con estos nuevos permisos otorgados, por simple y sencillo respeto a la ciudadan\u00eda que merece sabe el porqu\u00e9 las cosas se complicar\u00e1n todav\u00eda m\u00e1s con la aparici\u00f3n de nuevas ciudades en la zona metropolitana, cuando la demanda ha sido satisfecha y el riesgo de llevar a niveles cr\u00edticos la convivencia de una sociedad es m\u00e1s y m\u00e1s alto.<br \/>\u00a0\u00a0 \u00a0Peor a\u00fan si el argumento para ocultar el nombre de los ricos que se har\u00e1n m\u00e1s ricos a costa de todos, es ocultado porque les tienen un gran respeto, que por supuesto no existe hacia los habitantes de Pachuca.<br \/>\u00a0\u00a0 \u00a0Un error pat\u00e9tico y lamentable. M\u00e1s dinero a los que de por si ya tienen mucho, pero que no perder\u00e1n la oportunidad de hacerse de una buena cantidad de millones de pesos.<br \/>MINUTARIO.- MOVIMIENTO CIUDADANO se perfila como un partido que disputar\u00e1, y en serio, cargos de elecci\u00f3n popular en los comicios de 2018. Por fin un proyecto le cuajar\u00e1 al hombre poderoso de la Universidad Aut\u00f3noma del Estado de Hidalgo, Gerardo Sosa Castel\u00e1n, v\u00eda su hermano Dami\u00e1n. Luego de rotundo fracasos con otros experimentos, parece que el futuro le pinta bien y la tan ansiada senadur\u00eda ser\u00e1 una realidad.<\/p>\n<p>Mil gracias, hasta ma\u00f1ana.<br \/>jeperalta@plazajuarez.mx\/historico\/historico<br \/>@JavierEPeralta<br \/>\u00a0\u00a0 \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u2022\u00a0\u00a0 \u00a0M\u00e1s dinero a los fraccionadores\u2028\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0 \u00a0MINUTARIO\u2028<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-44823","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/44823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=44823"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/44823\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=44823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=44823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=44823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}