{"id":42974,"date":"2017-06-15T13:30:37","date_gmt":"2017-06-15T13:30:37","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/06\/15\/el-herido-steve-scalise-latigo-de-trump-en-el-congreso\/"},"modified":"2017-06-15T13:30:37","modified_gmt":"2017-06-15T13:30:37","slug":"el-herido-steve-scalise-latigo-de-trump-en-el-congreso","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/el-herido-steve-scalise-latigo-de-trump-en-el-congreso\/","title":{"rendered":"El herido Steve Scalise, l\u00e1tigo  de Trump en el Congreso"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Azote del pensamiento liberal, fue jefe del Comit\u00e9 de Estudios Republicanos, un grupo con m\u00e1s de 170 congresistas conservadores, donde promovi\u00f3 las ideas del libre mercado, la creaci\u00f3n de empleo, el crecimiento econ\u00f3mico o el apego estricto al esp\u00edritu literal de los mandatos de la Constituci\u00f3n. Scalise es un defensor a ultranza del derecho a las armas y es un pol\u00edtico muy cercano al lobby de la Asociaci\u00f3n Nacional del Rifle<\/p>\n<p>  <!--more-->  <\/p>\n<p>Steve Scalise, herido de bala en el ataque de ayer en Virginia, es el l\u00e1tigo de Donald Trump en el Congreso. Jefe de bancada de la mayor\u00eda republicana desde 2014, lo convierte en el tercer republicano de mayor rango en la C\u00e1mara de Representantes, su misi\u00f3n es lograr la unidad de filas en su partido cuando se vota una ley.<\/p>\n<p>Forjado desde joven en la pol\u00edtica de su estado de origen, Luisiana, estado por el que gan\u00f3 en 2008 su puesto como congresista en Washington, Scalise es un conservador con todas las credenciales ideol\u00f3gicas tipo de un republicano: cr\u00edtico del gasto p\u00fablico, partidario de bajar impuestos, favorable a invertir en defensa militar, conservador en valores.<\/p>\n<p>La victoria que m\u00e1s ha sudado en la legislatura actual ha sido la aprobaci\u00f3n del proyecto de ley para demoler el sistema de asistencia sanitaria Obamacare, que Trump convirti\u00f3 en una de sus promesas electorales y necesitaba poner en marcha. Pendiente de pasar por el Senado, la ley logr\u00f3 en mayo una victoria raspada en el Congreso con 217 votos a favor y 213 en contra -incluidos 20 republicanos que se le escaparon a Scalise y votaron con los dem\u00f3cratas-.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 Azote del pensamiento liberal, fue jefe del Comit\u00e9 de Estudios Republicanos, un grupo con m\u00e1s de 170 congresistas conservadores, donde promovi\u00f3 las ideas del libre mercado, la creaci\u00f3n de empleo, el crecimiento econ\u00f3mico o el apego estricto al esp\u00edritu literal de los mandatos de la Constituci\u00f3n. Scalise es un defensor a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-42974","post","type-post","status-publish","format-standard","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/42974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=42974"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/42974\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=42974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=42974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=42974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}