{"id":41615,"date":"2017-05-22T05:11:48","date_gmt":"2017-05-22T05:11:48","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/05\/22\/alfil-negro-795\/"},"modified":"2017-05-22T05:11:48","modified_gmt":"2017-05-22T05:11:48","slug":"alfil-negro-795","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/alfil-negro-795\/","title":{"rendered":"ALFIL NEGRO"},"content":{"rendered":"<p>(Nada hay m\u00e1s peligroso que un depredador herido, porque se convierte en una fuerza destructora sin ning\u00fan control, con la \u00fanica direcci\u00f3n de destruir, de atacar y de confrontarse con quien se le pare enfrente, animado por sus heridas y por el malestar que siente y que le obliga a buscar venganza o revancha. En pol\u00edtica al parecer pasa algo parecido, a quien supuestamente se le lastima o se le hiere se convierte en un depredador que\u00a0 buscar\u00e1 tarde que temprano la forma de vengarse o de cobrarse lo que considere ofensa o agresi\u00f3n que le haya lastimado en sus bienes, ubicaci\u00f3n o para\u00edsos que consideraba propios y que de hab\u00e9rsele quitado pensar\u00e1 que se le arrebataron de manera injusta, pues nunca aceptar\u00e1 que quien manda puede cambiar el cuadro de colaboradores de acuerdo a su modo de gobernar o de mejor servir a la sociedad, sin otro compromiso y m\u00e1s si\u00a0 para llegar al poder no cont\u00f3 con el apoyo de quienes se supone ten\u00edan la obligaci\u00f3n de hacerlo\u2026 En fin\u2026)<\/p>\n<p>  <!--more-->  <\/p>\n<p>SACAN LAS U\u00d1AS LOS RESENTIDOS Y DOLIDOS<br \/>El Gobernador OMAR FAYAD LLEG\u00d3 al poder de acuerdo al juicio de los observadores de la pol\u00edtica,\u00a0 principal y fundamentalmente por el apoyo ciudadano y dicen, muy poco o con un\u00a0 apoyo muy relativo\u00a0 de su partido y nada de\u00a0 apoyo de quienes en ese momento ten\u00edan el poder, quienes, dicen los que saben de esto, hicieron cuanto pudieron para que OMAR no llegara a ser gobernador.<br \/>Extra\u00f1o escenario, pero que al parecer se dio en Hidalgo.<br \/>Quiz\u00e1 por eso, con todo derecho y en una decisi\u00f3n l\u00f3gica el nuevo gobernador cuando fue la hora de dise\u00f1ar su equipo de colaboradores dej\u00f3 fuera a quienes por a\u00f1os hab\u00edan estado en los puestos claves de la administraci\u00f3n p\u00fablica con todas las obligaciones pero tambi\u00e9n con todos los privilegios que supone estar en esos cargos.<br \/>Es decir PROPUSO UNA NUEVA CLASE POL\u00cdTICA que en el fondo renueva caras e inicia ya en la pr\u00e1ctica un nuevo estilo de ejercer el poder, con todos los riesgos que puede haber, pero con todas las cosas buenas que puede traer el que venga aire nuevo en la administraci\u00f3n y el darle la oportunidad a gente joven,preparada y con ganas de hacer carrera y de servir al estado.<br \/>Toda esta nueva propuesta enmarcada bajo el signo de la eficacia y el combate frontal a la corrupci\u00f3n con todas sus consecuencias.<br \/>Con el bono del apoyo popular que no se puede olvidar y que se mantiene vigente en\u00a0 este d\u00eda, el 252 de su gobierno, porque la ciudadan\u00eda le tiene fe y confianza que es lo principal, pese a d\u00edceres que nunca faltan.<br \/>LAS CARAS NUEVAS\u2026<br \/>S\u00f3lo con estas medidas de dar oportunidades a j\u00f3venes brillantes es como se han podido ver a funcionarios talentosos como: ISRAEL F\u00c9LIX SOTO, J\u00c9SSICA BLANCAS, MARCO ANTONIO ESCAMILLA, SAYONARA VARGAS, JOS\u00c9 LUIS ROMO, CITALI JARAMILLO Y LAM\u00c1N CARRANZA entre otros. Sin m\u00e1s grupo pol\u00edtico que su talento y que conforme pasa el tiempo demuestran porque el Gobernador les dio el encargo donde se encuentran.<br \/>Desde luego con su llegada dejaron el cargo otros funcionarios que en muchos casos ten\u00edan ya muchos a\u00f1os en una secretar\u00eda o en otra, pero ya con una especie de propiedad en la administraci\u00f3n.<br \/>Para la mayor\u00eda de los ciudadanos la decisi\u00f3n del mandatario fue acertada. Para quienes se quedaron sin cargos no\u2026 ya veremos.<br \/>EN LOS \u00daLTIMOS 22 D\u00cdAS SACAN LAS U\u00d1AS<br \/>Si de suyo todo mundo sab\u00eda que la decisi\u00f3n de OMAR no hab\u00eda ca\u00eddo bien en los dejado sin sus \u201cpropiedades\u201d, se hab\u00edan cuidado de mantener cierta cordura de sus actitudes en el entendido de que quien manda, manda y de que como sea no les hab\u00eda ido mal cuando el sol les hab\u00eda pegada de frente.<br \/>Sin embargo era conocida su actitud de condena hacia el hecho de quedar fuera y sus juicios condenatorios en contra de los nuevos que de acuerdo a ellos no daban el ancho\u00a0 y menos se pod\u00edan comparar con \u201csus logros\u201d, aunque ya en los hechos los logros que se tienen est\u00e1n a la vista de todos y son buenos.<br \/>Pero desde que empez\u00f3 este mes de mayo como que se inici\u00f3 la rebeli\u00f3n de los dolidos que sacaron las u\u00f1as para reclamar sus derechos a los cargos y a las n\u00f3minas, porque s\u00ed. Las expresiones de algunos de ellos son no audaces sino groseras, porque no tienen mucha base para reclamar lo que a todas luces parece no tienen derecho, porque cuando debieron demostrar su real valer en bien de sus\u00a0 colores no lo hicieron. <br \/>El hecho de que se acerquen los d\u00edas de las decisiones para las candidaturas parece que les acelera el pulso para acercarse a su partido y ver y exigir lo que con acciones responsables no se han ganado. ALBERTO MEL\u00c9NDEZ hace milagros para mantener la unidad y para hacer valer la regla de oro de que el juicio del primer pri\u00edsta que es el gobernador es el que vale,porque los dolidos parece que lo han olvidado en sus corajes.<br \/>Se sabe de reuniones para fortalecer sus posturas.<br \/>No parece lo m\u00e1s correcto.<br \/>Se dice que el di\u00e1logo y los acuerdos hacen consensos que llevan a decisiones acertadas casi siempre.<br \/>\u00a0Las confrontaciones no son buenas. Y menos cuando llevan el ingrediente del chantaje.<br \/>As\u00ed se ve el panorama\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Nada hay m\u00e1s peligroso que un depredador herido, porque se convierte en una fuerza destructora sin ning\u00fan control, con la \u00fanica direcci\u00f3n de destruir, de atacar y de confrontarse con quien se le pare enfrente, animado por sus heridas y por el malestar que siente y que le obliga a buscar venganza o revancha. En [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-41615","post","type-post","status-publish","format-standard","hentry","category-nuestrapalabra"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/41615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=41615"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/41615\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=41615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=41615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=41615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}