{"id":40955,"date":"2017-05-10T20:02:37","date_gmt":"2017-05-10T20:02:37","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/05\/10\/realizan-mami-fitness-en-la-explanada-de-plaza-independencia\/"},"modified":"2017-05-10T20:02:37","modified_gmt":"2017-05-10T20:02:37","slug":"realizan-mami-fitness-en-la-explanada-de-plaza-independencia","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/realizan-mami-fitness-en-la-explanada-de-plaza-independencia\/","title":{"rendered":"Realizan \u201cMami Fitness\u201d en la explanada de Plaza Independencia"},"content":{"rendered":"<p style=\"text-align: justify;\">Con la participaci\u00f3n entusiasta de m\u00e1s de 300 pachuque\u00f1os, incluyendo a madres de familia con sus hijos, se llev\u00f3 a cabo la macro activaci\u00f3n f\u00edsica \u201cMami Fitness\u201d en la explanada de Plaza Independencia, promovida por el Sistema DIF Pachuca y el Instituto Municipal del Deporte como una alternativa para mantener el equilibrio f\u00edsico y emocional a trav\u00e9s del ejercicio.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Con el Reloj Monumental enmarcando el evento, rodeado con m\u00f3dulos de asesor\u00eda jur\u00eddica, de servicios m\u00e9dicos b\u00e1sicos y de talleres para mujeres, Paola Ludlow Teller\u00eda, presidenta del DIF capitalino afirm\u00f3 que la Instituci\u00f3n que preside trabaja por el bienestar de las familias con actividades que fomentan la cultura de la prevenci\u00f3n y el cuidado de la salud.<\/p>\n<p style=\"text-align: justify;\">\u201cCon esta actividad el ayuntamiento de Pachuca da inicio a las acciones que tendremos durante el mes de mayo para conmemorar el D\u00eda de las Madres, brindando pl\u00e1ticas y talleres a mujeres, principalmente a quienes son madres de familia para detonar su econom\u00eda por medio de la capacitaci\u00f3n y el emprendimiento\u201d.<\/p>\n<p style=\"text-align: justify;\">Asimismo, inform\u00f3 que el pr\u00f3ximo 25 de mayo en el Centro Cultural El Reloj, a trav\u00e9s del voluntariado del DIF municipal, se ofrecer\u00e1 la conferencia \u201cPilares fuertes, familias exitosas\u201d con el objetivo de empoderar a las mujeres, toda vez que juegan un rol muy importante dentro del tejido social.<\/p>\n<p style=\"text-align: justify;\">Por otra parte, la alcaldesa Yolanda Teller\u00eda agradeci\u00f3 la participaci\u00f3n de los asistentes, reconociendo el trabajo que realizan las madres de familia para construir familias m\u00e1s fuertes.<\/p>\n<p style=\"text-align: justify;\">\u201cLas mam\u00e1s\u00a0 son uno de los principales cimientos en la sociedad, si trabajamos con ellas para dejar la semilla de los valores, lograremos que Pachuca sea un mejor municipio\u201d, puntualiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la participaci\u00f3n entusiasta de m\u00e1s de 300 pachuque\u00f1os, incluyendo a madres de familia con sus hijos, se llev\u00f3 a cabo la macro activaci\u00f3n f\u00edsica \u201cMami Fitness\u201d en la explanada de Plaza Independencia, promovida por el Sistema DIF Pachuca y el Instituto Municipal del Deporte como una alternativa para mantener el equilibrio f\u00edsico y emocional [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-40955","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/40955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=40955"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/40955\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=40955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=40955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=40955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}