{"id":39921,"date":"2017-04-20T12:35:00","date_gmt":"2017-04-20T12:35:00","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2017\/04\/20\/insistira-yoli-para-que-fondo-metropolitano-sea-invertido-en-ampliar-pachuca-en-bici\/"},"modified":"2017-04-20T12:35:00","modified_gmt":"2017-04-20T12:35:00","slug":"insistira-yoli-para-que-fondo-metropolitano-sea-invertido-en-ampliar-pachuca-en-bici","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/insistira-yoli-para-que-fondo-metropolitano-sea-invertido-en-ampliar-pachuca-en-bici\/","title":{"rendered":"Insistir\u00e1 Yoli para que Fondo Metropolitano sea invertido en ampliar Pachuca en Bici"},"content":{"rendered":"<p>Aprovechar rutas de ciclov\u00edas existentes para mejorar transporte<\/p>\n<p>  <!--more-->  <\/p>\n<p>Luego de la presentaci\u00f3n del redise\u00f1o del programa Bici Capital, ahora nombrado Pachuca en Bici, la alcaldesa Yolanda Teller\u00eda Beltr\u00e1n asegur\u00f3 que buscar\u00e1 durante su gesti\u00f3n que parte del fondo metropolitano sea dirigido a mejorar la conectividad de las ciclov\u00edas principalmente con las zonas universitarias.<br \/>En este tema record\u00f3 que de acuerdo a la reestructuraci\u00f3n que proponen para conectar las zonas universitarias de San Agust\u00edn Tlaxiaca y Mineral de la Reforma se requieren de los 36 millones de pesos del fondo metropolitano que actualmente el gobierno del estado propone invertir en la nueva estaci\u00f3n del Tuzobus en direcci\u00f3n a la central.<br \/>Agreg\u00f3 que seguir\u00e1n apelando para que su propuesta sea considerada durante su administraci\u00f3n y en caso de que este a\u00f1o no se pueda realizar, volver\u00e1n a integrar la propuesta para el siguiente a\u00f1o. \u201cTristemente el fondo metropolitano hoy se desv\u00eda a otros destinos pero vamos a estar apostando para poder lograrlo\u201d.<br \/>No obstante mencionaron que el plan para el mejoramiento de este programa pretende aprovechar las v\u00edas ya existentes, adem\u00e1s de que de acuerdo de las necesidades de la poblaci\u00f3n se buscar\u00e1 llegar al sur de la ciudad y ampliar el n\u00famero de estaciones.<br \/>Con la restructuraci\u00f3n del programa tambi\u00e9n se present\u00f3 la nueva membres\u00eda para los usuarios que mantendr\u00e1 el mismo costo de 365 pesos y que podr\u00e1 ser pagada con tarjeta o en efectivo en cualquiera de las ciclo estaciones como Prepa 3, Maestranza, Sendero de las Am\u00e9ricas, Jard\u00edn de Hombres Ilustres, Complejo Revoluci\u00f3n Mexicana, Luis Pasteur y Centro Hist\u00f3rico.<br \/>Aunado a ello, Teller\u00eda Beltr\u00e1n record\u00f3 que se trabaja en algunas modificaciones dentro del reglamento de tr\u00e1nsito\u00a0 con la intenci\u00f3n de proteger a los usuarios y de igual manera, analizar las nuevas rutas que habr\u00e1n de conectar a las zonas universitarias para no poner en riesgo la vida de los estudiantes quienes se planea, sean los principales usuarios. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprovechar rutas de ciclov\u00edas existentes para mejorar transporte<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-39921","post","type-post","status-publish","format-standard","hentry","category-pachuca"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/39921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=39921"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/39921\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=39921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=39921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=39921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}