{"id":33058,"date":"2016-12-07T21:07:03","date_gmt":"2016-12-07T21:07:03","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2016\/12\/07\/premian-a-ganadores-de-concurso-de-dibujo-infantil\/"},"modified":"2016-12-07T21:07:03","modified_gmt":"2016-12-07T21:07:03","slug":"premian-a-ganadores-de-concurso-de-dibujo-infantil","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/premian-a-ganadores-de-concurso-de-dibujo-infantil\/","title":{"rendered":"Premian a ganadores de concurso de dibujo infantil"},"content":{"rendered":"<p style=\"text-align: justify;\"><span lang=\"ES-TRAD\">Inform\u00f3 el Consejo Estatal de Poblaci\u00f3n que el pasado 9 de noviembre del 2016 se llev\u00f3 a cabo en la Secretar\u00eda T\u00e9cnica, la selecci\u00f3n de los dibujos ganadores en las diferentes categor\u00edas de la etapa estatal, del XXIII Concurso Nacional de Dibujo Infantil y Juvenil, 2016; <\/span><span lang=\"ES\">\u201cEn M\u00e9xico Luchamos por el Respeto. Convivencia Libre de Violencia\u201d<\/span><span lang=\"ES-TRAD\">.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-TRAD\">De acuerdo con el organismo, el concurso es organizado por el Consejo Nacional de Poblaci\u00f3n, los Consejos Estatales de Poblaci\u00f3n y el Fondo de Poblaci\u00f3n de las Naciones Unidas desde 1992 y cada a\u00f1o se abordan diferentes tem\u00e1ticas que ata\u00f1en a la poblaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-TRAD\">El certamen, apunt\u00f3, est\u00e1 dividido en dos etapas: la primera es la estatal, y los dibujos que obtuvieron los primeros lugares en sus respectivas categor\u00edas participaron en la fase nacional, en la que se seleccionaron los mejores dibujos del pa\u00eds de un total de 18,703 participantes. <\/span><\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-TRAD\">En este sentido, detall\u00f3 que se llev\u00f3 a cabo la Ceremonia de Premiaci\u00f3n de la fase estatal en la Sala de Exgobernadores de Palacio de Gobierno del Poder Ejecutivo del Gobierno del Estado de Hidalgo, reconociendo a ni\u00f1os, adolescentes y j\u00f3venes que a trav\u00e9s de sus dibujos muestran como quieren vivir sin violencia ya sea en su hogar, escuela o comunidad convirti\u00e9ndose en superh\u00e9roes del respeto.<\/span><\/p>\n<p style=\"text-align: justify;\">En esta ocasi\u00f3n se recibieron un total de 2,067 dibujos provenientes de todas las regiones que conforman nuestro Estado, y por categor\u00edas se repartieron de la siguiente manera: 678 de la \u201cA\u201d (de 6 a 9 a\u00f1os); 709 de la \u201cB\u201d (10 a 12 a\u00f1os); 173 de la \u201cC\u201d (13 a 15 a\u00f1os); 329 de la \u201cD\u201d (16 a 19 a\u00f1os) y 178 de la \u201cE\u201d (de 20 a 24 a\u00f1os).<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/poblacion.hidalgo.gob.mx\/?p=1619\"><span style=\"font-size: 12.16px; text-align: start;\">AQU\u00cd LOS DIBUJOS DE LA FASE ESTATAL<\/span><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Los ganadores de la etapa estatal son:<\/strong><\/p>\n<p style=\"text-align: justify;\">Categor\u00eda A (de 6 a 9 a\u00f1os)<\/p>\n<p style=\"text-align: justify;\">PRIMER LUGAR<\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES\">Yaretzi Citlalli Torres Guzm\u00e1n<\/span>, 8 a\u00f1os, Pachuca de Soto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">SEGUNDO LUGAR<\/p>\n<p style=\"text-align: justify;\">Brandon Alejandro P\u00e9rez Bautista, 9 a\u00f1os, Pachuca de Soto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">TERCER LUGAR<\/p>\n<p style=\"text-align: justify;\">Ximena Silva Castillo, 9 a\u00f1os, Molango de Escamilla.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Categor\u00eda B (de 10 a 12 a\u00f1os)<\/p>\n<p style=\"text-align: justify;\">PRIMER LUGAR<\/p>\n<p style=\"text-align: justify;\">Shareth Aranti Caranza Mart\u00ednez, 12 a\u00f1os, Santiago Tulantepec.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">SEGUNDO LUGAR<\/p>\n<p style=\"text-align: justify;\">Omar L\u00f3pez Verde, 12 a\u00f1os, Pachuca de Soto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">TERCER LUGAR<\/p>\n<p style=\"text-align: justify;\">Alan Einar Peralta Lozano, 10 a\u00f1os, Molango de Escamilla.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Categor\u00eda C (de 13 a 15 a\u00f1os)<\/p>\n<p style=\"text-align: justify;\">PRIMER LUGAR<\/p>\n<p style=\"text-align: justify;\">Gabriela Ramos Rend\u00f3n, 14 a\u00f1os, Pachuca de Soto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">SEGUNDO LUGAR<\/p>\n<p style=\"text-align: justify;\">Emiliano Mart\u00ednez Mej\u00eda, 14 a\u00f1os, Pachuca de Soto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">TERCER LUGAR<\/p>\n<p style=\"text-align: justify;\">Adile Ingrid L\u00f3pez Carrillo, 15 a\u00f1os, Pachuca de Soto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Categor\u00eda D (de 16 a 19 a\u00f1os)<\/p>\n<p style=\"text-align: justify;\">PRIMER LUGAR<\/p>\n<p style=\"text-align: justify;\">Bartolo Leonel Hern\u00e1ndez Ju\u00e1rez, 18 a\u00f1os, Zacualtip\u00e1n de \u00c1ngeles.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">SEGUNDO LUGAR<\/p>\n<p style=\"text-align: justify;\">Fernando Cano Granados, 19 a\u00f1os, Francisco I. Madero.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">TERCER LUGAR<\/p>\n<p style=\"text-align: justify;\">Gerzain Reyes Cort\u00e9s, 17 a\u00f1os, Xochicoatl\u00e1n.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Categor\u00eda E (de 20 a 24 a\u00f1os)<\/p>\n<p style=\"text-align: justify;\">PRIMER LUGAR<\/p>\n<p style=\"text-align: justify;\">Sa\u00fal Esteban Gonz\u00e1lez, 24 a\u00f1os, Calnali.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">SEGUNDO LUGAR<\/p>\n<p style=\"text-align: justify;\">Uriel Mera Hern\u00e1ndez, 21 a\u00f1os, Francisco I. Madero.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">TERCER LUGAR<\/p>\n<p style=\"text-align: justify;\">Diego Emilio Santiago, 20 a\u00f1os, Huejutla de Reyes.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inform\u00f3 el Consejo Estatal de Poblaci\u00f3n que el pasado 9 de noviembre del 2016 se llev\u00f3 a cabo en la Secretar\u00eda T\u00e9cnica, la selecci\u00f3n de los dibujos ganadores en las diferentes categor\u00edas de la etapa estatal, del XXIII Concurso Nacional de Dibujo Infantil y Juvenil, 2016; \u201cEn M\u00e9xico Luchamos por el Respeto. Convivencia Libre de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-33058","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/33058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=33058"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/33058\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=33058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=33058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=33058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}