{"id":304328,"date":"2024-04-06T04:00:00","date_gmt":"2024-04-06T10:00:00","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=304328"},"modified":"2024-04-05T22:53:46","modified_gmt":"2024-04-06T04:53:46","slug":"se-incendia-bodega-de-materias-primas-en-acatlan","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/se-incendia-bodega-de-materias-primas-en-acatlan\/","title":{"rendered":"Se incendia bodega de materias primas en Acatl\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>ACATL\u00c1N.- <\/strong>La madrugada de este viernes 5 de abril se incendi\u00f3 una bodega de materias primas e insumos en el municipio de Acatl\u00e1n, dejando \u00fanicamente cuantiosas p\u00e9rdidas materiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afortunadamente, el siniestro no dej\u00f3 saldo de personas heridas ni tampoco p\u00e9rdida de vidas humanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el reporte de Protecci\u00f3n Civil municipal, la deflagraci\u00f3n ocurri\u00f3 aproximadamente a las 6:00 de la ma\u00f1ana, hora en la que llegaron los uniformados tras un reporte ciudadano de vecinos de la colonia Agust\u00edn Olvera, donde ocurrieron los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reportaron que sobre la calle Cedros, una fuerte llamarada se esparc\u00eda por el establecimiento, sin embargo, el cuerpo de Bomberos report\u00f3 que logr\u00f3 controlarse por completo, sin representar da\u00f1os colaterales a vecinos ni saldo de heridos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se precisaron las causas del incendio, ni tampoco se cuantifican los da\u00f1os materiales, pero el c\u00e1lculo de los afectados era motivo de preocupaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACATL\u00c1N.- La madrugada de este viernes 5 de abril se incendi\u00f3 una bodega de materias primas e insumos en el municipio de Acatl\u00e1n, dejando \u00fanicamente cuantiosas p\u00e9rdidas materiales. Afortunadamente, el siniestro no dej\u00f3 saldo de personas heridas ni tampoco p\u00e9rdida de vidas humanas. De acuerdo con el reporte de Protecci\u00f3n Civil municipal, la deflagraci\u00f3n ocurri\u00f3 [&hellip;]<\/p>\n","protected":false},"author":70,"featured_media":304329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-304328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/304328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=304328"}],"version-history":[{"count":1,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/304328\/revisions"}],"predecessor-version":[{"id":304330,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/304328\/revisions\/304330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/304329"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=304328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=304328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=304328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}