{"id":2973,"date":"2015-03-29T06:00:00","date_gmt":"2015-03-29T06:00:00","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2015\/03\/29\/milicias-islamistas-toman-el-control-de-la-provincia-siria-de-idlib\/"},"modified":"2015-03-29T06:00:00","modified_gmt":"2015-03-29T06:00:00","slug":"milicias-islamistas-toman-el-control-de-la-provincia-siria-de-idlib","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/milicias-islamistas-toman-el-control-de-la-provincia-siria-de-idlib\/","title":{"rendered":"Milicias islamistas toman el control  de la provincia siria de Idlib"},"content":{"rendered":"<p>Siria.- Las milicias islamistas han derrotado a las fuerzas gubernamentales en la ciudad de Idlib tras una violenta batalla que ha durado cuatro d\u00edas, inform\u00f3 el Observatorio Sirio para los Derechos Humanos, organizaci\u00f3n con sede en Londres y con una amplia red de informantes en el territorio del pa\u00eds \u00e1rabe.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00a0<\/p>\n<p>En los \u00faltimos combates han muerto al menos siete milicianos rebeldes y tambi\u00e9n habr\u00eda v\u00edctimas y numerosos capturados entre las filas del Ej\u00e9rcito. Los aviones del r\u00e9gimen contin\u00faan bombardeando las posiciones de los islamistas.<\/p>\n<p>En la ofensiva contra las fuerzas del r\u00e9gimen sirio han participado milicias como Ahrar al Sham, Jund al Aqsa, los Batallones Isl\u00e1micos o el Frente al Nusra, filial de Al Qaeda en Siria. Ahora estos milicianos est\u00e1n registrando la ciudad casa por casa en busca de soldados del Ej\u00e9rcito sirio.<\/p>\n<p>Con la ca\u00edda de la ciudad, la provincia de Idlib se convierte en la segunda provincia del pa\u00eds que ya no est\u00e1 en manos de las fuerzas gubernamentales, despu\u00e9s de que Raqqa pasara a ser controlada por el Estado Isl\u00e1mico, que ha convertido esta ciudad en la capital de su califato. (Agencias)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siria.- Las milicias islamistas han derrotado a las fuerzas gubernamentales en la ciudad de Idlib tras una violenta batalla que ha durado cuatro d\u00edas, inform\u00f3 el Observatorio Sirio para los Derechos Humanos, organizaci\u00f3n con sede en Londres y con una amplia red de informantes en el territorio del pa\u00eds \u00e1rabe.<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-2973","post","type-post","status-publish","format-standard","hentry","category-orbe"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=2973"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/2973\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=2973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}