{"id":295012,"date":"2024-01-13T03:57:19","date_gmt":"2024-01-13T09:57:19","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=295012"},"modified":"2024-01-13T03:57:21","modified_gmt":"2024-01-13T09:57:21","slug":"sentencian-a-50-anos-de-prision-a-un-responsable-de-secuestro","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/sentencian-a-50-anos-de-prision-a-un-responsable-de-secuestro\/","title":{"rendered":"Sentencian a 50 a\u00f1os de prisi\u00f3n a un responsable de secuestro"},"content":{"rendered":"\n<p>Investigaciones de agentes del Ministerio P\u00fablico adscritos a la Unidad Especializada en el Combate al Secuestro (UECS) de la Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH), sirvieron para que el tribunal de enjuiciamiento dictara sentencia condenatoria de 50 a\u00f1os de prisi\u00f3n para responsable del delito de secuestro agravado.<\/p>\n\n\n\n<p>Los hechos, por los cuales una persona identificada con iniciales E. R. M., fue investigada, ocurrieron en noviembre de 2021 en el municipio de Tizayuca, cuando la v\u00edctima fue privada de su libertad y posteriormente para su liberaci\u00f3n a sus familiares les fue exigido dinero en efectivo para su rescate.<\/p>\n\n\n\n<p>Derivado de lo ocurrido los hechos fueron denunciados ante el Ministerio P\u00fablico, por lo que la PGJEH inici\u00f3 la carpeta de investigaci\u00f3n de la que se hicieron cargo agentes adscritos a la UECS.<\/p>\n\n\n\n<p>Con base en labores de inteligencia y un operativo t\u00e1ctico en la colonia Felipe \u00c1ngeles, del municipio ya mencionado, se logr\u00f3 el rescate de la v\u00edctima y la detenci\u00f3n del responsable del secuestro, identificado con iniciales E. R. M.<\/p>\n\n\n\n<p>Los agentes del Ministerio P\u00fablico encargados de las investigaciones reunieron los datos de prueba suficientes contra el imputado y lo presentaron ante la autoridad judicial. Durante la audiencia inicial, esta representaci\u00f3n social formul\u00f3 la imputaci\u00f3n y un juez de control dict\u00f3 el auto de vinculaci\u00f3n a proceso para E. R. M.<\/p>\n\n\n\n<p>Al finalizar todas las etapas del proceso penal, un tribunal de enjuiciamiento dict\u00f3 sentencia condenatoria de 50 a\u00f1os de prisi\u00f3n para el responsable de secuestro agravado, as\u00ed como tambi\u00e9n se impuso una multa econ\u00f3mica y el pago por concepto de la reparaci\u00f3n del da\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investigaciones de agentes del Ministerio P\u00fablico adscritos a la Unidad Especializada en el Combate al Secuestro (UECS) de la Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH), sirvieron para que el tribunal de enjuiciamiento dictara sentencia condenatoria de 50 a\u00f1os de prisi\u00f3n para responsable del delito de secuestro agravado. Los hechos, por los cuales [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":295013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-295012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/295012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=295012"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/295012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/295013"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=295012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=295012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=295012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}