{"id":292820,"date":"2023-12-21T10:05:24","date_gmt":"2023-12-21T16:05:24","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=292820"},"modified":"2023-12-21T10:05:26","modified_gmt":"2023-12-21T16:05:26","slug":"lopez-obrador-hablara-por-telefono-con-biden-sobre-migracion","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/lopez-obrador-hablara-por-telefono-con-biden-sobre-migracion\/","title":{"rendered":"L\u00f3pez Obrador hablar\u00e1 por tel\u00e9fono con Biden sobre migraci\u00f3n"},"content":{"rendered":"\n<p>El presidente mexicano, Andr\u00e9s Manuel L\u00f3pez Obrador, revel\u00f3 que hablar\u00e1 por tel\u00e9fono la ma\u00f1ana de este jueves con el mandatario de Estados Unidos, Joe Biden, con quien abordar\u00e1 la migraci\u00f3n.<\/p>\n\n\n\n<p>\u201cTengo una llamada precisamente con el presidente Biden, a las 9:00 (15:00 GMT). Yo creo que (el tema ser\u00e1) migraci\u00f3n, \u00e9l pidi\u00f3 hablar conmigo y, desde luego, me va a dar mucho gusto saludarlo y que conversemos\u201d, declar\u00f3 L\u00f3pez Obrador en su rueda de prensa diaria.<\/p>\n\n\n\n<p>La llamada ocurrir\u00e1 tras la reuni\u00f3n de ambos mandatarios el 17 de noviembre en el Foro de Cooperaci\u00f3n Econ\u00f3mica Asia-Pac\u00edfico (APEC, en ingl\u00e9s) que se celebr\u00f3 en la ciudad estadounidense de San Francisco, donde acordaron reforzar la cooperaci\u00f3n para contener la migraci\u00f3n irregular y el tr\u00e1fico de fentanilo.<\/p>\n\n\n\n<p>L\u00f3pez Obrador insisti\u00f3 entonces a Biden en que EE.UU. debe apoyar un plan de cooperaci\u00f3n para Latinoam\u00e9rica tras la cumbre migratoria que alberg\u00f3 M\u00e9xico el 22 de octubre con Belice, Colombia, Costa Rica, Cuba, El Salvador, Hait\u00ed, Honduras, Panam\u00e1 y Venezuela, que concluy\u00f3 con un rechazo a las \u201cmedidas coercitivas\u201d y la petici\u00f3n de m\u00e1s alternativas legales para la migraci\u00f3n.<\/p>\n\n\n\n<p>El gobernante mexicano no ofreci\u00f3 m\u00e1s detalles sobre su llamada con el presidente de Estados Unidos, donde la pol\u00e9mica sobre la migraci\u00f3n se intensifica en medio de la contienda interna de los republicanos y la nueva ley antimigrantes de Texas que autoriza a jueces y polic\u00edas locales detener a indocumentados y deportarlos.<\/p>\n\n\n\n<p>\u201cVamos a ver qu\u00e9 nos plantea, \u00e9l (Biden) pidi\u00f3 ayer que quiere hablar conmigo y con mucho gusto. Yo creo que es (una charla) normal, en una de esas es por la Navidad\u201d, concluy\u00f3 L\u00f3pez Obrador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente mexicano, Andr\u00e9s Manuel L\u00f3pez Obrador, revel\u00f3 que hablar\u00e1 por tel\u00e9fono la ma\u00f1ana de este jueves con el mandatario de Estados Unidos, Joe Biden, con quien abordar\u00e1 la migraci\u00f3n. \u201cTengo una llamada precisamente con el presidente Biden, a las 9:00 (15:00 GMT). Yo creo que (el tema ser\u00e1) migraci\u00f3n, \u00e9l pidi\u00f3 hablar conmigo y, [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":292821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-292820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/292820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=292820"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/292820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/292821"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=292820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=292820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=292820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}