{"id":2800,"date":"2015-03-26T06:00:00","date_gmt":"2015-03-26T06:00:00","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2015\/03\/26\/lunes-informan-a-san-miguel-tlazintla-los-avances-de-la-obra-de-rehabilitacion\/"},"modified":"2015-03-26T06:00:00","modified_gmt":"2015-03-26T06:00:00","slug":"lunes-informan-a-san-miguel-tlazintla-los-avances-de-la-obra-de-rehabilitacion","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/lunes-informan-a-san-miguel-tlazintla-los-avances-de-la-obra-de-rehabilitacion\/","title":{"rendered":"Lunes informan a San Miguel Tlazintla  los avances de la obra de rehabilitaci\u00f3n"},"content":{"rendered":"<p><strong>El Cardonal<\/strong><\/p>\n<ul>\n<li><strong>Reuni\u00f3n de personal de la Comisi\u00f3n Estatal del Agua y Alcantarillado con integrantes del sistema de agua potable<\/strong><\/li>\n<li><strong><strong>Se prev\u00e9 que a mediados de julio se concluyan los trabajos<\/strong><\/strong> <!--more--> <\/li>\n<\/ul>\n<p>El pr\u00f3ximo lunes seis de abril, personal de la Comisi\u00f3n Estatal del Agua y Alcantarillado (CEAA) y su titular, Juan Mart\u00edn Habib Nicol\u00e1s, se reunir\u00e1n con integrantes del sistema de agua potable de San Miguel Tlazintla, para informar sobre los avances de la obra.<\/p>\n<p>Francisco Cruz Ch\u00e1vez, vicepresidente del sistema, sostuvo que existe una excelente coordinaci\u00f3n con las autoridades del gobierno del estado, asimismo acuerdos, los cuales permitir\u00e1n que el seis de abril, se realice esta reuni\u00f3n informativa.<\/p>\n<p>Ayer, integrantes del sistema, se reunieron con funcionario de la Subsecretar\u00eda de Gobernaci\u00f3n, esto en respuesta a la solicitud que hicieron al Gobernador, Francisco Olvera Ruiz, para que se agilicen los trabajos de rehabilitaci\u00f3n del sistema de agua potable.<\/p>\n<p>Alejandro Ram\u00edrez Furiati, Subsecretario de Gobernaci\u00f3n, sostuvo que ha habido una mala informaci\u00f3n, sin embargo esta reuni\u00f3n sirvi\u00f3 para poder llegar a acuerdos, entre ellos que ser\u00e1 la CEAA quien acuda al Sauz, comunidad de El Cardonal, donde mantendr\u00e1n un encuentro con representantes de las ocho comunidades que conforman el sistema para informarles las condiciones de los trabajos.<\/p>\n<p>Explic\u00f3, que hasta el momento la rehabilitaci\u00f3n del sistema lleva un avance del 60 por ciento, los recursos superiores a los 15 millones de pesos autorizados en 2014 ya se est\u00e1n ejecutando y se prev\u00e9 que m\u00e1ximo a mediados de julio se concluyan los trabajos.<\/p>\n<p>Existe una petici\u00f3n por parte de los integrantes del sistema, relacionado a que en el \u00faltimo kil\u00f3metro y medio de tuber\u00eda, pretenden incrementar de las ocho pulgadas autorizadas a 10, para que el vital l\u00edquido sea mayor, asimismo un nuevo tanque de almacenamiento para resolver la escasez en las zonas altas.<\/p>\n<p>Debido a que esas peticiones no se encuentran en el proyecto original, solicitar\u00e1n al delegado de la Comisi\u00f3n Nacional del Agua (Conagua), realice el proyecto y otorgue las autorizaciones correspondientes para evitar posibles violaciones a la ley.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cardonal Reuni\u00f3n de personal de la Comisi\u00f3n Estatal del Agua y Alcantarillado con integrantes del sistema de agua potable Se prev\u00e9 que a mediados de julio se concluyan los trabajos<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-2800","post","type-post","status-publish","format-standard","hentry","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/2800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=2800"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/2800\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=2800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=2800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=2800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}