{"id":278486,"date":"2023-08-30T08:07:55","date_gmt":"2023-08-30T14:07:55","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=278486"},"modified":"2023-08-30T08:08:01","modified_gmt":"2023-08-30T14:08:01","slug":"grutas-de-tolantongo-tendra-carretera-con-inversion-de-58-mdp","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/grutas-de-tolantongo-tendra-carretera-con-inversion-de-58-mdp\/","title":{"rendered":"Grutas de Tolantongo, tendr\u00e1 carretera con inversi\u00f3n de 58 mdp"},"content":{"rendered":"\n<p><strong>EL CARDONAL<\/strong>.- El gobierno de Hidalgo, modernizar\u00e1 el camino rural de El Palmar, Santiago de Anaya- Pozuelos- El Cardonal, que conecta con la carretera federal, M\u00e9xico-Laredo, para facilitar el traslado de turistas que se dirigen a las Grutas de Tolantongo.\u00a0<\/p>\n\n\n\n<p>En la primera etapa, de acuerdo a la Secretar\u00eda de Infraestructura, se van a invertir m\u00e1s de 58 millones de pesos, los cuales se aplicar\u00e1n en poco m\u00e1s de cinco kil\u00f3metros de modernizaci\u00f3n de esta v\u00eda corta, que reducir\u00e1 hasta una hora el traslado de los automovilistas.&nbsp;<\/p>\n\n\n\n<p>Los trabajos de modernizaci\u00f3n de la carretera, comenzar\u00e1n en las pr\u00f3ximas semanas y podr\u00edan estar listas en los siguientes meses antes que concluya el a\u00f1o, para que en 2024 se destine la segunda etapa.<\/p>\n\n\n\n<p>Este proyecto, adem\u00e1s de detonar econ\u00f3micamente a las comunidades de los municipios de Santiago de Anaya y El Cardonal, se va a permitir reducir el tiempo de traslado de los turistas, asimismo, conectar a estos poblados con la carretera federal y la capital del estado.&nbsp;<\/p>\n\n\n\n<p>Cabe se\u00f1alar, que esta carretera, tiene por lo menos 10 a\u00f1os que se ha planteado al gobierno del estado. Se busca que los visitantes eviten el paso por Ixmiquilpan, que los alcanza a demorar por m\u00e1s de una hora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL CARDONAL.- El gobierno de Hidalgo, modernizar\u00e1 el camino rural de El Palmar, Santiago de Anaya- Pozuelos- El Cardonal, que conecta con la carretera federal, M\u00e9xico-Laredo, para facilitar el traslado de turistas que se dirigen a las Grutas de Tolantongo.\u00a0 En la primera etapa, de acuerdo a la Secretar\u00eda de Infraestructura, se van a invertir [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":278487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2159,40],"tags":[],"class_list":["post-278486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-hidalgo","category-region"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/278486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=278486"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/278486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/278487"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=278486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=278486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=278486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}