{"id":26385,"date":"2016-08-09T13:35:07","date_gmt":"2016-08-09T13:35:07","guid":{"rendered":"http:\/\/plazajuarez.mx\/index\/index.php\/2016\/08\/09\/imparte-casa-de-las-y-los-adolescentes-taller-de-muralismo-urbano\/"},"modified":"2016-08-09T13:35:07","modified_gmt":"2016-08-09T13:35:07","slug":"imparte-casa-de-las-y-los-adolescentes-taller-de-muralismo-urbano","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/imparte-casa-de-las-y-los-adolescentes-taller-de-muralismo-urbano\/","title":{"rendered":"Imparte Casa de las y los Adolescentes  taller de muralismo urbano"},"content":{"rendered":"<p>&#8212;\u00a0 El Sistema DIF Hidalgo a trav\u00e9s de la Casa de las y los Adolescentes convoca a participar en este taller<\/p>\n<p>  <!--more-->  <\/p>\n<p>A diferencia del graffiti, el muralismo urbano es una actividad que se adapta al contexto, es por ello que la Casa de las y los Adolescentes en vinculaci\u00f3n con el Instituto Municipal para la Juventud de Pachuca promueve el taller de muralismo urbano.<br \/>\u201cEl muralismo urbano lo que hace es utilizar el contexto y transformarlo de tal manera que le da una imagen diferente y entonces lejos de ser una imagen fr\u00eda le da vida\u201d, cit\u00f3 el coordinador de Casa de las y los Adolescentes, Fernando P\u00e9rez Romero.<br \/>Por lo anterior, el Sistema DIF Hidalgo a trav\u00e9s de la Casa de las y los Adolescentes convoca a participar en este taller que se imparte de manera gratuita los d\u00edas martes y jueves, con el objetivo de que las y los participantes descubran en el muralismo una forma de expresi\u00f3n, as\u00ed como una herramienta para detonar su creatividad.<br \/>En la primera fase del taller las y los adolescentes participar\u00e1n en un proceso de preparaci\u00f3n te\u00f3rica para comprender el muralismo urbano y, posteriormente,\u00a0 en la parte pr\u00e1ctica, elaborar\u00e1n un mural en la pared del skatorama que tiene alrededor de 25 metros, ubicado en las instalaciones de la Casa de las y los Adolescentes.<br \/>Un mural que tendr\u00e1 diferentes etapas, pues se piensa dividir el muro para que m\u00e1s chicos se sumen a este proceso creativo, expuso Fernando P\u00e9rez Romero, quien reiter\u00f3 la invitaci\u00f3n a conocer las actividades de Casa de las y los Adolescentes.<br \/>En la p\u00e1gina oficial de Casa de las y los Adolescentes en Facebook las personas interesadas pueden conocer las actividades y horarios en que est\u00e1n programadas; tambi\u00e9n pueden solicitar informaci\u00f3n a los tel\u00e9fonos 107 2655 y 107 2357. La Casa de las y los Adolescentes est\u00e1 ubicada en boulevard Everardo M\u00e1rquez esquina con avenida Revoluci\u00f3n, en la colonia Periodistas de Pachuca. <\/p>\n<p>EN LA PRIMERA FASE DEL TALLER LAS Y LOS <br \/>ADOLESCENTES PARTICIPAR\u00c1N EN UN PROCESO<br \/>\u00a0DE PREPARACI\u00d3N TE\u00d3RICA PARA COMPRENDER<br \/>\u00a0EL MURALISMO URBANO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8212;\u00a0 El Sistema DIF Hidalgo a trav\u00e9s de la Casa de las y los Adolescentes convoca a participar en este taller<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-26385","post","type-post","status-publish","format-standard","hentry","category-pachuca"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/26385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=26385"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/26385\/revisions"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=26385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=26385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=26385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}