{"id":262029,"date":"2023-05-20T06:32:19","date_gmt":"2023-05-20T12:32:19","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=262029"},"modified":"2023-05-20T09:16:46","modified_gmt":"2023-05-20T15:16:46","slug":"presencia-de-pumas-en-la-entidad-sinonimo-del-buen-estado-de-los-ecosistemas","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/presencia-de-pumas-en-la-entidad-sinonimo-del-buen-estado-de-los-ecosistemas\/","title":{"rendered":"Presencia de Pumas en la entidad, sin\u00f3nimo del buen estado de los ecosistemas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Medio Ambiente y Recursos Naturales de Hidalgo (SEMARNATH), asegur\u00f3 que en la entidad se tiene un buen estado de conservaci\u00f3n, lo anterior derivado de la presencia de pumas en el territorio hidalguense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de sus redes sociales, la dependencia puntualiz\u00f3 que el puma concolor, conocido popularmente como le\u00f3n de monta\u00f1a o le\u00f3n americano, es una especie exclusiva de Am\u00e9rica, que se distribuye desde el sur de Canad\u00e1 hasta el sur de Argentina y Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ala que esta especie puede vivir en casi todos los ecosistemas, desde los \u00e1ridos, semi\u00e1ridos, templados y tropicales, como el matorral, bosques, zonas monta\u00f1osas y por las noches incluso en pastizales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detalla que se encuentra activo principalmente al amanecer y al anochecer, por lo que, tiene h\u00e1bitos crepusculares y requieren grandes extensiones de terreno para su sobrevivencia, que suele ir de 10 mil a 15 mil hect\u00e1reas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, destac\u00f3 que derivado de los monitoreos que realiza a trav\u00e9s de c\u00e1maras trampas han identificado su presencia en Hidalgo, lo que confirma el buen estado de conservaci\u00f3n de los ecosistemas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Medio Ambiente y Recursos Naturales de Hidalgo (SEMARNATH), asegur\u00f3 que en la entidad se tiene un buen estado de conservaci\u00f3n, lo anterior derivado de la presencia de pumas en el territorio hidalguense. A trav\u00e9s de sus redes sociales, la dependencia puntualiz\u00f3 que el puma concolor, conocido popularmente como le\u00f3n de monta\u00f1a o [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":262030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,59,2159],"tags":[],"class_list":["post-262029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-general","category-noticias-de-hidalgo"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/262029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=262029"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/262029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/262030"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=262029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=262029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=262029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}