{"id":261936,"date":"2023-05-19T09:12:42","date_gmt":"2023-05-19T15:12:42","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=261936"},"modified":"2023-05-19T09:12:42","modified_gmt":"2023-05-19T15:12:42","slug":"gonzalo-celorio-se-alza-con-el-villaurrutia","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/gonzalo-celorio-se-alza-con-el-villaurrutia\/","title":{"rendered":"Gonzalo Celorio se alza con el Villaurrutia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El escritor Gonzalo Celorio es el ganador del Premio Xavier Villaurrutia de Escritores para Escritores 2022 por su libro Mentideros de la memoria, que posee un &#8220;profundo anclaje en la tradici\u00f3n de la mejor literatura hispanoamericana, a trav\u00e9s de una prosa de gran expresividad y belleza&#8221;. Una obra que recopila an\u00e9cdotas autobiogr\u00e1ficas donde los protagonistas son grandes autores de la literatura hispanoamericana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo determin\u00f3 el jurado del galard\u00f3n, integrado por Pura L\u00f3pez Colom\u00e9, Marianne Toussaint y Fernando Fern\u00e1ndez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el comunicado donde se dio la noticia, Celorio dijo sentirse conmovido y emocionado al resultar ganador de este premio. Dijo que como profesor de letras y como ensayista, ha dedicado muchas horas de estudio a la literatura. &#8220;Es un premio que recibo a una edad ya tard\u00eda, en un momento en el que ya tengo una larga trayectoria y, aunque sea un premio dedicado a un libro en particular, creo que el jurado tambi\u00e9n pudo haber considerado una larga trayectoria, de muchos a\u00f1os dedicados a la literatura&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Mentideros de la memoria&#8221; re\u00fane una veintena de textos referidos a otros tantos escritores con quienes tuve el privilegio de sostener un di\u00e1logo y, en algunos casos, una amistad estrecha. En este libro doy mi testimonio sobre di\u00e1logos literarios que compart\u00ed con escritores como Julio Cort\u00e1zar, Carlos Fuentes, Augusto Monterroso, Humberto Eco, Dulce Mar\u00eda Loynaz, Eliseo Diego, Juan Rulfo, entre otros&#8221;, agreg\u00f3 el escritor, profesor de literatura y acad\u00e9mico de la lengua nacido en 1948, dijo que esta obra merecedora del Premio Villaurrutia que dividi\u00f3 en 20 cap\u00edtulos, es un libro h\u00edbrido, pues contiene una parte narrativa, otra ensay\u00edstica, una testimonial y tambi\u00e9n cr\u00edtica literaria. Un libro que escribi\u00f3 entre 2020 y 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ceremonia de entrega del galard\u00f3n ser\u00e1 en la Sala Manuel M. Ponce del Palacio de Bellas Artes, en fecha por definir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El escritor Gonzalo Celorio es el ganador del Premio Xavier Villaurrutia de Escritores para Escritores 2022 por su libro Mentideros de la memoria, que posee un &#8220;profundo anclaje en la tradici\u00f3n de la mejor literatura hispanoamericana, a trav\u00e9s de una prosa de gran expresividad y belleza&#8221;. Una obra que recopila an\u00e9cdotas autobiogr\u00e1ficas donde los protagonistas [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":261948,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-261936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/261936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=261936"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/261936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/261948"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=261936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=261936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=261936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}