{"id":259660,"date":"2023-04-30T10:46:48","date_gmt":"2023-04-30T16:46:48","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=259660"},"modified":"2023-04-30T10:46:51","modified_gmt":"2023-04-30T16:46:51","slug":"rosalia-2","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/rosalia-2\/","title":{"rendered":"\u00bfRosal\u00eda puede ser sancionada por alterar los s\u00edmbolos patrios?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> La cantante espa\u00f1ola Rosal\u00eda ofreci\u00f3 este viernes un concierto gratuito en el Z\u00f3calo que cont\u00f3 con la asistencia de 160 mil personas; el tema del evento deriv\u00f3 en temas pol\u00edticos por el cuestionamiento del presupuesto utilizado para pagarle, aunque OCESA asegur\u00f3 que la int\u00e9rprete de &#8220;Despech\u00e1&#8221; no cobr\u00f3 monto alguno por presentarse en Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el evento masivo en el que se cont\u00f3 con la asistencia de 160 mil personas, fan\u00e1ticos y algunos cr\u00edticos del evento compartieron fotograf\u00edas de la cantante en la que destac\u00f3 una imagen donde aparece sentada con una serie de peluches &#8220;Simi&#8221; que le han lanzado en sus conciertos en M\u00e9xico y como fondo tambi\u00e9n se encuentra la bandera del pa\u00eds rayada con el nombre de su \u00e1lbum &#8220;Motomami&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fotograf\u00eda que circula en redes se public\u00f3 al finalizar el concierto de la espa\u00f1ola en el Auditorio de la Ciudad de M\u00e9xico en 2022. Si bien los elementos que mostr\u00f3 la espa\u00f1ola fueron regalos de sus fans, en redes sociales le cuestionaron sobre cu\u00e1nto iba a pagar por el da\u00f1o a la Bandera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 sanciones puedes tener si da\u00f1as los s\u00edmbolos patrios?<br>En M\u00e9xico el da\u00f1o a la Bandera o a cualquiera de los s\u00edmbolos patrios como el Escudo o el Himno Nacional puede ser sancionado con multas o el arresto. De acuerdo con el art\u00edculo 191 del C\u00f3digo Penal Federal establecen que quien la altere o da\u00f1e puede ser acreedor a seis meses o hasta cuatro a\u00f1os de prisi\u00f3n, as\u00ed como una multa de 50 a tres mil pesos.<br>En la Ley sobre el Escudo, la Bandera y el Himno determinan las caracter\u00edsticas que deben poseer cada uno, adem\u00e1s del uso y difusi\u00f3n de estos, para que en caso de alterarse, la Secretar\u00eda de Gobernaci\u00f3n pueda analizar la situaci\u00f3n y asignar la sanci\u00f3n correspondiente.<br>Al finalizar su concierto, la int\u00e9rprete del &#8220;Malquerer&#8221; agradeci\u00f3 a sus seguidores en M\u00e9xico. &#8220;Uno de los d\u00edas m\u00e1s felices de mi vida. Gracias a todos los que vinisteis y llenasteis el Z\u00f3calo. Este ha sido el concierto m\u00e1s grande que he dado en mi carrera. M\u00e9xico tienes para siempre mi coraz\u00f3n&#8221;, expres\u00f3 en su cuenta de Instagram.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cantante espa\u00f1ola Rosal\u00eda ofreci\u00f3 este viernes un concierto gratuito en el Z\u00f3calo que cont\u00f3 con la asistencia de 160 mil personas; el tema del evento deriv\u00f3 en temas pol\u00edticos por el cuestionamiento del presupuesto utilizado para pagarle, aunque OCESA asegur\u00f3 que la int\u00e9rprete de &#8220;Despech\u00e1&#8221; no cobr\u00f3 monto alguno por presentarse en Ciudad de [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":259324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-259660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/259660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=259660"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/259660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/259324"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=259660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=259660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=259660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}