{"id":259646,"date":"2023-04-30T10:06:39","date_gmt":"2023-04-30T16:06:39","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=259646"},"modified":"2023-04-30T12:09:20","modified_gmt":"2023-04-30T18:09:20","slug":"pg","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/pg\/","title":{"rendered":"Cuatro agresores de Polic\u00edas a disposici\u00f3n de PGJEH"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El viernes dispararon a agentes, en camino viejo al Geiser de Progreso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH), recibi\u00f3 la puesta a disposici\u00f3n de cuatro personas, tres de ellas por ultrajes a la autoridad y una m\u00e1s por homicidio doloso calificado en grado de tentativa, en agravio de elementos de la Polic\u00eda Estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche del viernes 28 de abril 2023, se recibi\u00f3 aviso sobre detonaciones de arma de fuego en el camino viejo al geiser, en el municipio de Progreso de Obreg\u00f3n, raz\u00f3n por la que agentes de la polic\u00eda estatal se trasladaron al lugar de los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el sitio resultaron agredidos f\u00edsicamente y con arma de fuego por parte de los imputados, quienes fueron detenidos en ese momento y puestos a disposici\u00f3n de la PGJEH.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la agresi\u00f3n result\u00f3 lesionado por disparo de arma de fuego un elemento de la Secretar\u00eda de Seguridad P\u00fablica de Hidalgo (SSPH), quien fue trasladado a un hospital para recibir atenci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico integra la carpeta de investigaci\u00f3n y se allega de datos de prueba contra las personas imputadas identificadas con las iniciales M. F. O. C., L. M. G., B. D. T. A., y M. L. G., este \u00faltimo por homicidio doloso calificado, en grado de tentativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas detenidas ser\u00e1n presentadas ante la autoridad judicial para formularles imputaci\u00f3n y solicitar su vinculaci\u00f3n a proceso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes dispararon a agentes, en camino viejo al Geiser de Progreso La Procuradur\u00eda General de Justicia del Estado de Hidalgo (PGJEH), recibi\u00f3 la puesta a disposici\u00f3n de cuatro personas, tres de ellas por ultrajes a la autoridad y una m\u00e1s por homicidio doloso calificado en grado de tentativa, en agravio de elementos de la [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":259648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-259646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barandilla"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/259646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=259646"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/259646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/259648"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=259646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=259646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=259646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}