{"id":246240,"date":"2023-01-12T22:13:43","date_gmt":"2023-01-13T04:13:43","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=246240"},"modified":"2023-01-12T22:13:51","modified_gmt":"2023-01-13T04:13:51","slug":"lisa-marie-presley-fallece-a-los-54-anos-tras-sufrir-un-paro-cardiaco","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/lisa-marie-presley-fallece-a-los-54-anos-tras-sufrir-un-paro-cardiaco\/","title":{"rendered":"Lisa Marie Presley fallece a los 54 a\u00f1os tras sufrir un paro card\u00edaco"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La \u00fanica hija de Elvis Presley, Lisa Marie Presley, falleci\u00f3 este jueves a los 54 a\u00f1os tras haber sido hospitalizada a causa de un paro card\u00edaco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Con el coraz\u00f3n encogido debo compartir la devastadora noticia de que mi hermosa hija Lisa Marie nos ha dejado. Era la mujer m\u00e1s apasionada, fuerte y cari\u00f1osa que he conocido&#8221;, expres\u00f3 Priscilla Presley, madre de Lisa Marie, en un comunicado enviado a la revista especializada en celebridades People.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje llega despu\u00e9s de que la cantante hubiera sido reportada en estado cr\u00edtico tras haber sido inducida a un coma y de que su madre pidiera en redes sociales a la gente que la mantuvieran &#8220;en sus oraciones&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el medio estadounidense de celebridades TMZ, que tambi\u00e9n confirm\u00f3 la muerte de Presley, el jueves recibi\u00f3 primeros auxilios y fue asistida por param\u00e9dicos en su casa ubicada en Calabasas (California) tras haber sufrido problemas card\u00edacos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de ser trasladada, los especialistas m\u00e9dicos lograron recuperar el pulso de la cantante y una vez que lleg\u00f3 al hospital su vida fue asistida con un marcapasos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana, la hija del astro del rock and roll fue vista en la gala de los Globos de Oro junto a su madre, Priscilla Presley, como acompa\u00f1antes del actor Austin Butler, quien gan\u00f3 el premio a mejor actor de drama por su papel de Elvis Presley en el filme de Baz Luhrmann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lisa Marie Presley fue la \u00fanica hija del ic\u00f3nico cantante y madre de cuatro hijos, entre ellos la actriz y cineasta estadounidense Riley Keough.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presley sigui\u00f3 los pasos de su padre y en 2003 lanz\u00f3 su primer \u00e1lbum, &#8220;To Whom it May Concern&#8221;, y a este le siguieron dos producciones m\u00e1s, pero desde 2012 no hab\u00eda sacado ning\u00fan disco nuevo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00fanica hija de Elvis Presley, Lisa Marie Presley, falleci\u00f3 este jueves a los 54 a\u00f1os tras haber sido hospitalizada a causa de un paro card\u00edaco. &#8220;Con el coraz\u00f3n encogido debo compartir la devastadora noticia de que mi hermosa hija Lisa Marie nos ha dejado. Era la mujer m\u00e1s apasionada, fuerte y cari\u00f1osa que he [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":246241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,38],"tags":[],"class_list":["post-246240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-show"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/246240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=246240"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/246240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/246241"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=246240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=246240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=246240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}