{"id":245911,"date":"2023-01-11T14:28:24","date_gmt":"2023-01-11T20:28:24","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=245911"},"modified":"2023-01-11T14:31:23","modified_gmt":"2023-01-11T20:31:23","slug":"sedeco_-6","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/sedeco_-6\/","title":{"rendered":"Imparte Sedeco cursos para empoderar a mujeres en el rol econ\u00f3mico"},"content":{"rendered":"\n<p>Con el prop\u00f3sito de que las mujeres identifiquen su rol econ\u00f3mico en el \u00e1mbito familiar y personal, as\u00ed como erradicar ideas y creencias que limitan su vida financiera, la Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco) a trav\u00e9s del Instituto Hidalguense de Competitividad Empresarial (IHCE) imparti\u00f3 diversos cursos de capacitaci\u00f3n.<\/p>\n\n\n\n<p>Entre los temas desarrollados, destaca el de&nbsp; \u201cMujeres en el contexto proveedor\u201d.<\/p>\n\n\n\n<p>Estas acciones permiten empoderar a este sector poblacional e influir en el estilo de vida, as\u00ed como el reconocimiento de la violencia econ\u00f3mica que en muchas ocasiones ejercen sus parejas sobre ellas, mencion\u00f3 el titular de la dependencia, Carlos Henkel Escorza.<\/p>\n\n\n\n<p>La modalidad del curso fue virtual, el cual fue impartido por el psicol\u00f3gico Obed de Jes\u00fas Montiel, quien expuso las diferentes alternativas que las mujeres tienen para su independencia econ\u00f3mica, el emprendedurismo y la creaci\u00f3n de sus propias empresas, las cuales incluso pueden generar fuentes de empleo.<\/p>\n\n\n\n<p>Las participantes interactuaron con el expositor a fin de empoderarse en un mundo globalizado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el prop\u00f3sito de que las mujeres identifiquen su rol econ\u00f3mico en el \u00e1mbito familiar y personal, as\u00ed como erradicar ideas y creencias que limitan su vida financiera, la Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco) a trav\u00e9s del Instituto Hidalguense de Competitividad Empresarial (IHCE) imparti\u00f3 diversos cursos de capacitaci\u00f3n. Entre los temas desarrollados, destaca el de&nbsp; [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":245912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,59,2159],"tags":[],"class_list":["post-245911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-general","category-noticias-de-hidalgo"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/245911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=245911"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/245911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/245912"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=245911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=245911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=245911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}