{"id":245894,"date":"2023-01-11T13:59:03","date_gmt":"2023-01-11T19:59:03","guid":{"rendered":"https:\/\/plazajuarez.mx\/?p=245894"},"modified":"2023-01-11T13:59:10","modified_gmt":"2023-01-11T19:59:10","slug":"ataque_gomez","status":"publish","type":"post","link":"https:\/\/plazajuarez.mx\/historico\/ataque_gomez\/","title":{"rendered":"\u00bfCu\u00e1nto tiempo vigilaron a G\u00f3mez Leyva antes del ataque?"},"content":{"rendered":"\n<p>El secretario de Seguridad Ciudadana, Omar Garc\u00eda Harfuch se\u00f1al\u00f3 que hay otros veh\u00edculos implicados en el ataque contra el periodista, Ciro G\u00f3mez Leyva, y que hasta ahora aseguraron un veh\u00edculo Seat Ibiza, un Corsa color gris, un Acura color negro, y una motocicleta.<\/p>\n\n\n\n<p>Al ejecutar diferentes \u00f3rdenes de cateo en por los menos 12 inmuebles, se aseguraron un total de ocho veh\u00edculos, uno de ellos es un veh\u00edculo blindado; cinco motocicletas; diversos dispositivos electr\u00f3nicos y de comunicaci\u00f3n; documentaci\u00f3n diversa y animales ex\u00f3ticos: tres perros lobo y un mapache.<\/p>\n\n\n\n<p>&#8212;\u00bfCu\u00e1nto tiempo vigilaron al periodista Ciro G\u00f3mez Leyva?<\/p>\n\n\n\n<p>Garc\u00eda Harfuch inform\u00f3 que derivado del an\u00e1lisis de los videos de C5, as\u00ed como de c\u00e1maras de circuitos cerrados privadas recabados, fue posible identificar que los presuntos responsables de la agresi\u00f3n viajaban a bordo de un veh\u00edculo color negro que sirvi\u00f3 como muro durante el ataque y una motocicleta color negro con naranja tripulada por dos personas.<\/p>\n\n\n\n<p>Se inform\u00f3 que los agresores tuvieron presencia y vigilancia en las inmediaciones de Grupo Imagen donde trabaja la v\u00edctima los d\u00edas 6 de diciembre, 10, 11, 12 y 13 de diciembre en horarios de la tarde noche, principalmente siendo captado en varias ocasiones el veh\u00edculo Seat Ibiza color negro.<\/p>\n\n\n\n<p>&#8212;El d\u00eda de la agresi\u00f3n contra Ciro G\u00f3mez Leyva<\/p>\n\n\n\n<p>Antes de la agresi\u00f3n, a las 10:42 de la noche se observa la llegada, esto antes de la agresi\u00f3n, de un veh\u00edculo Seat Ibiza color negro a las inmediaciones de Grupo Imagen, estacion\u00e1ndose a las 10:44 de la noche sobre avenida Universidad, a la altura de la calle Benito Ju\u00e1rez.<\/p>\n\n\n\n<p>Tambi\u00e9n, a las 10:42 se identifica la llegada del veh\u00edculo Chevrolet Corsa color gris al punto de avenida Universidad y Miguel \u00c1ngel de Quevedo, del cual desciende una persona misma que se observa que cruza avenida Universidad para reunirse con el conductor de la motocicleta a las 10:45 de la noche.<\/p>\n\n\n\n<p>A las 10:58, el veh\u00edculo Corsa arriba al cruce de la calle Carmelita y Vito Alessio Robles en la colonia Florida de la Alcald\u00eda \u00c1lvaro Obreg\u00f3n, donde permaneci\u00f3 estacionado. A las 11 de la noche se observa la salida de la camioneta color gris conducida por el periodista posterior a eso el veh\u00edculo Seat Ibiza color negro comienza a darle seguimiento sobre avenida de la Universidad llegando hasta el cruce de la calle Cerro Acasullco donde rebasa la camioneta para colocarse en la parte de adelante mientras que la camioneta con los dos sicarios daba seguimiento a la camioneta en la parte de atr\u00e1s.<\/p>\n\n\n\n<p>Dicho veh\u00edculo de color negro permaneci\u00f3 siempre delante de la camioneta y justo disminuy\u00f3 su velocidad en el punto donde se efectu\u00f3 la agresi\u00f3n para que ah\u00ed pudiera ser alcanzada por tripulantes de la motocicleta y estos en posibilidad de efectuar los disparos en contra de la v\u00edctima lo que ocurri\u00f3 a las 11:10 de la noche aproximadamente.<\/p>\n\n\n\n<p>Tras el ataque armado, los agresores huyeron en diferentes direcciones, por lo que hace la motocicleta en la que iban a bordo del piloto y el responsable de llevar a cabo los disparos, a las 11:12 se observa su paso sobre avenida Insurgentes, Barranca del Muerto y Parroquia al oriente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Seguridad Ciudadana, Omar Garc\u00eda Harfuch se\u00f1al\u00f3 que hay otros veh\u00edculos implicados en el ataque contra el periodista, Ciro G\u00f3mez Leyva, y que hasta ahora aseguraron un veh\u00edculo Seat Ibiza, un Corsa color gris, un Acura color negro, y una motocicleta. Al ejecutar diferentes \u00f3rdenes de cateo en por los menos 12 inmuebles, [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":245897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,36],"tags":[],"class_list":["post-245894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacion"],"_links":{"self":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/245894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/comments?post=245894"}],"version-history":[{"count":0,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/posts\/245894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media\/245897"}],"wp:attachment":[{"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/media?parent=245894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/categories?post=245894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazajuarez.mx\/historico\/wp-json\/wp\/v2\/tags?post=245894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}